{"id":6891,"date":"2017-10-30T19:11:48","date_gmt":"2017-10-30T19:11:48","guid":{"rendered":"http:\/\/www.galiciamaxica.eu\/mini\/?p=6891"},"modified":"2024-08-13T19:18:38","modified_gmt":"2024-08-13T17:18:38","slug":"castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia","status":"publish","type":"post","link":"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/","title":{"rendered":"Castro Laboreiro, A Escusalla y Castelo de Lindoso en un d\u00eda"},"content":{"rendered":"<p style=\"text-align: center;\">Los s\u00e1bados tambi\u00e9n est\u00e1n para madrugar porque para un viaje como el de hoy<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.galiciamaxica.eu\/mini\/temas-conversar-ninos-cuanto-falta\/\"> necesitaremos de tiempo<\/a><\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afc554f6bb.jpg\" alt=\"\" width=\"1025\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Hoy visitaremos tres lugares muy especiales,<\/p>\n<p style=\"text-align: center;\">nos moveremos de Galicia a Portugal y de Portugal a Galicia como si de un viaje espacio-tiempo se tratase<\/p>\n<p style=\"text-align: center;\"><strong>para descubrir lugares con muchas historias y leyendas<\/strong><\/p>\n<p style=\"text-align: center;\"><iframe src=\"https:\/\/www.google.com\/maps\/d\/embed?mid=1_VWPfMCEkzYF_0LqUNxoxpTA8wU\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/\">Castro Laboreiro<\/a>, A\u00a0<a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/casa-da-escusalla\/\">Escusalla <\/a>y <a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castillo-lindoso\/\">Lindoso<\/a><\/strong> un tri\u00e1ngulo m\u00e1gico que nos aportar\u00e1 un viaje top en nuestra agenda.<\/p>\n<p style=\"text-align: center;\">Nos iban surgiendo de camino pr\u00f3ximos viajes que anotamos con muchas ganas de realizar.<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afc5be5348.jpg\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Nuestra primera parada de la ma\u00f1ana para estirar las piernas y hablar de lo que ibamos a ver, fue en<\/p>\n<h2 style=\"text-align: center;\">PORTA DE LAMAS DE MOURO<\/h2>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/puente-cava-da-velha-ponte-nova\/\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afc620c55f.jpg\" alt=\"\" width=\"433\" height=\"769\" \/><\/a><\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 658px; padding: 0; width: calc(100% - 2px);\" data-instgrm-captioned=\"\" data-instgrm-version=\"7\">\n<div style=\"padding: 8px;\">\n<div style=\"background: #F8F8F8; line-height: 0; margin-top: 40px; padding: 50.0% 0; text-align: center; width: 100%;\"><\/div>\n<p style=\"margin: 8px 0 0 0; padding: 0 4px;\"><a style=\"color: #000; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none; word-wrap: break-word;\" href=\"https:\/\/www.instagram.com\/p\/BazM23dn4Uw\/\" target=\"_blank\" rel=\"noopener noreferrer\">Buenas tardes a todos!!<\/a><\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\">Una publicaci\u00f3n compartida de Mar\u00eda Rodr\u00edguez Serantes (@seseixa) el <time style=\"font-family: Arial,sans-serif; font-size: 14px; line-height: 17px;\" datetime=\"2017-10-28T17:26:21+00:00\">28 de Oct de 2017 a la(s) 10:26 PDT<\/time><\/p>\n<\/div>\n<\/blockquote>\n<p><script async=\"\" defer=\"\" src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script><\/p>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/www.turismoenportugal.org\/que-ver-en-el-parque-nacional-de-peneda-geres\">Situado en el Parque nacional de Peneda-Ger\u00eas<\/a><\/h2>\n<p style=\"text-align: center;\"><iframe src=\"https:\/\/www.youtube.com\/embed\/Rw1ljKwPmmQ\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"text-align: center;\">Nombrado reserva de la biosfera, por parte de la UNESCO.<\/p>\n<figure style=\"width: 433px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/ZiwNwJ9A3GwN72_XxF42bAUZf26x1ftQnQjzbzISkDbNpwYXOpC0mr4pmn9sB2b95O3Cxsg1EjwMPx_FlfUbsqO6cX6Bh9i6FVlvSX2vKVF6XqTemUdkp_v6oGtGU8M-Ne0ncdY3HdUeRdraf0HT5BkFPCd8j4QaSqovqH2Ax7r6PB1rI8ewF7zUNf3WgE8wg8KwPY_dQ9D7fAiejFvd5Av_5tv1RzSGWVV8HXzYKx-w37hzTX879_H-KlR-ZR6e_n-cIrBVZjboxlNjb07jSgbzOeCnPc_zm5gdcuiSqqwaZn2S80xxJ8unQgYVfxXNszGjBFzau2CRnecJYG3geuzbmQMvJ7P-ffGy4ObQDsk5tglVADNPcpB09qwOGdQeRWtezAkPR9oWs-WCFyiB5hfRhpCAcnlndFqjd_UM9uRoB98vYcKO-okQL5ZOpeyTkeQzR6oP6aL6Gh6iD35Tm2wF4g0XiOpWgdZwMpEjM6O0A5sERrZ6waFb4EM9zlP-4GaLF1FeaQ-2qEfb29RbNHKt_NtRC07TwGqsIERVGUPRmhyfC9rhcZK6678-Lvy30efCP3kKfm0RAg_yMNQPpz0LNubOxtDfYL6bT1eHwFA=w433-h769-no\" alt=\"\" width=\"433\" height=\"769\" \/><figcaption class=\"wp-caption-text\"><strong>Foto de Adhara<\/strong><\/figcaption><\/figure>\n<p style=\"text-align: center;\">Un merendero con amplia zona de aparcamiento y muchas mesas, as\u00ed como servicios y restaurantes<\/p>\n<p style=\"text-align: center;\">nuestro punto de inicio para un viaje que lo iba a tener todo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afc6363837.gif\" width=\"334\" height=\"500\" \/><\/p>\n<p style=\"text-align: center;\">Una mini vuelta a nuestro mundo o un paseo por dos pa\u00edses con mucho en com\u00fan,<\/p>\n<p style=\"text-align: center;\">seg\u00fan quien lo mire.<\/p>\n<figure style=\"width: 542px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.cocinarpara2.com\/empanada-de-jamon-y-queso\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afc6890780.jpg\" alt=\"\" width=\"542\" height=\"769\" \/><\/a><figcaption class=\"wp-caption-text\"><a href=\"http:\/\/www.cocinarpara2.com\/empanada-de-jamon-y-queso\">En el viaje no pod\u00eda faltar su petici\u00f3n<\/a><\/figcaption><\/figure>\n<p style=\"text-align: center;\">Seguimos nuestra ruta despu\u00e9s del breve descanso, disfrutando con lo que nos ofrece el paisaje de Portugal y<\/p>\n<p style=\"text-align: center;\">ya de camino nos vamos encontrando lugares con encanto<\/p>\n<figure style=\"width: 433px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afc70826db.jpg\" alt=\"\" width=\"433\" height=\"769\" \/><figcaption class=\"wp-caption-text\"><strong>Garita de vigilancia<\/strong><\/figcaption><\/figure>\n<p style=\"text-align: center;\"><em><strong>\u201cAquello que habita en el pasado y aquello que habita en el futuro es s\u00f3lo una peque\u00f1a cosa comparado con aquello que habita dentro de nosotros\u201d<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>\u00a0Ralph Waldo Emerson<\/strong><\/em><\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/ponte-velha-de-castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afc793d0c7.jpg\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Sabemos que cada viaje te regala experiencias por eso nuestra recomendaci\u00f3n es<\/p>\n<p style=\"text-align: center;\">\u00abvete disfrutando de cada lugar\u00bb, mira poco el reloj, aprende mucho, emp\u00e1pate con los sitios\u00a0 y sobre todo s\u00e9 feliz.<\/p>\n<p style=\"text-align: center;\">Solemos pensar que los rincones m\u00e1gicos te encuentran a ti y no al rev\u00e9s, as\u00ed que si ves de camino uno,<\/p>\n<h2 style=\"text-align: center;\">para y disfr\u00fatalo!<\/h2>\n<blockquote class=\"wp-embedded-content\" data-secret=\"T5PGISwIPy\"><p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/ponte-velha-de-castro-laboreiro\/\">Ponte Velha de Castro Laboreiro<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abPonte Velha de Castro Laboreiro\u00bb \u2014 Galicia M\u00e1xica | Algo m\u00e1s que ver en Galicia\" src=\"https:\/\/www.galiciamaxica.eu\/portugal\/ponte-velha-de-castro-laboreiro\/embed\/#?secret=sAX82CZAsT#?secret=T5PGISwIPy\" data-secret=\"T5PGISwIPy\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p style=\"text-align: center;\">El tiempo lo marc\u00e1is vosotros y el viaje est\u00e1 en continua construcci\u00f3n, en proceso de cambios, puedes pautar puntos interesantes pero estamos seguros de que encontrar\u00e1s de camino otros muchos que merecen si cabe m\u00e1s la visita.<\/p>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/ponte-velha-de-castro-laboreiro\/\">Ponte Velha<\/a><\/h2>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/ponte-velha-de-castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afc85ba342.jpg\" alt=\"\" width=\"433\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Cada uno hace suyo el lugar y le saca todo el partido posible, lo que para unos es patrimonio, para otros es una foto top con precioso encuadre o por qu\u00e9 no, un lugar en el que divertirte practicando tu deporte favorito<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/g.co\/kgs\/BNkoGP\">Parkour <\/a><\/p>\n<p><a href=\"https:\/\/photos.app.goo.gl\/Meq8nZQ0VgllKhvR2\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6893 size-medium aligncenter\" src=\"http:\/\/www.galiciamaxica.eu\/mini\/wp-content\/uploads\/2017\/10\/tren-turistico-223x300.jpg\" alt=\"\" width=\"223\" height=\"300\" srcset=\"https:\/\/www.galiciamaxica.eu\/mini\/wp-content\/uploads\/2017\/10\/tren-turistico-223x300.jpg 223w, https:\/\/www.galiciamaxica.eu\/mini\/wp-content\/uploads\/2017\/10\/tren-turistico.jpg 430w\" sizes=\"(max-width: 223px) 100vw, 223px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Cruzamos con cuidado el puente porque no hay barandillas \ud83d\ude09 y la altura es considerable,<\/p>\n<h4 style=\"text-align: center;\">recomendamos precauci\u00f3n con ni\u00f1@s peque\u00f1os,<\/h4>\n<h4 style=\"text-align: center;\">recuerda nosotros como adultos debemos anticiparnos y conocer primero los peligros en los sitios<\/h4>\n<h4 style=\"text-align: center;\">para prever y avisar de los mismos.<\/h4>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/ponte-velha-de-castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afc887f6d5.gif\" alt=\"\" width=\"432\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Mires a d\u00f3nde mires, el lugar nos invita a la visita en otra estaci\u00f3n porque debe ser incre\u00edble ver el agua cayendo<\/p>\n<p style=\"text-align: center;\">en forma de fervenza y apreciar los nuevos colores que transformar\u00e1n todo.<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/ponte-velha-de-castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afc8fab0c4.jpg\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">El puente est\u00e1 arropado en un paisaje de valles incre\u00edble, vamos a tomarnos tiempo contempl\u00e1ndolo todo<\/p>\n<p style=\"text-align: center;\"><strong>no hay prisa<\/strong><\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/ponte-velha-de-castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afc9d4580d.jpg\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<h2 style=\"text-align: center;\">Porque<\/h2>\n<p style=\"text-align: center;\">La naturaleza es maravillosa si se sabe disfrutar con los cinco sentidos<\/p>\n<h2 style=\"text-align: center;\">y<\/h2>\n<p><a href=\"http:\/\/www.galiciamaxica.eu\/mini\/hoy-naturaleza\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afca7eee89.jpg\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<h2 style=\"text-align: center;\">Porque<\/h2>\n<p style=\"text-align: center;\">Disfrutar de la <a href=\"http:\/\/www.galiciamaxica.eu\/mini\/hoy-naturaleza\/\">naturaleza<\/a> y la vida es necesario para ser feliz.<\/p>\n<p><a href=\"http:\/\/www.galiciamaxica.eu\/mini\/hoy-naturaleza\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afca99d2de.jpg\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Al lado del puente un molino que aprovechando la fuerza del agua mover\u00eda la rueda para moler cereales<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/ponte-velha-de-castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcab656eb.jpg\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">y para llegar a \u00e9l, solo has de cruzar el puente, siempre mejor por el medio del mismo<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/ponte-velha-de-castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcadc9188.gif\" alt=\"\" width=\"850\" height=\"478\" \/><\/a><\/p>\n<p style=\"text-align: center;\">y nos ense\u00f1ar\u00e1 otra salida diferente de por donde entramos.<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/ponte-velha-de-castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcb11a019.jpg\" alt=\"\" width=\"433\" height=\"769\" \/><\/a><\/p>\n<h2 style=\"text-align: center;\">Ahora nos vamos al <a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/\">Castelo de Laboreiro<\/a><\/h2>\n<blockquote class=\"wp-embedded-content\" data-secret=\"eq4agU76Qt\"><p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/\">Castillo de Castro Laboreiro<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abCastillo de Castro Laboreiro\u00bb \u2014 Galicia M\u00e1xica | Algo m\u00e1s que ver en Galicia\" src=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/embed\/#?secret=HgqKto6Pq3#?secret=eq4agU76Qt\" data-secret=\"eq4agU76Qt\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<h2 style=\"text-align: center;\">tambi\u00e9n conocido como <a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/\">Castro Laboreiro<\/a><\/h2>\n<p style=\"text-align: center;\">Antes de ir os recomiendo ver este\u00a0video, es muy interesante para descubrir a d\u00f3nde vamos<\/p>\n<p style=\"text-align: center;\">\u00bfentenderemos el portugu\u00e9s? seguro que s\u00ed<\/p>\n<p style=\"text-align: center;\"><iframe src=\"https:\/\/www.youtube.com\/embed\/V3I4LVZnxJ8\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2 style=\"text-align: center;\">Y ya en el lugar contarles esta leyenda<\/h2>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcb1f2bce.jpg\" alt=\"\" width=\"1153\" height=\"769\" \/><\/a><\/p>\n<h2><a href=\"#leyenda\">Leyenda de do\u00f1a Sancha Rodr\u00edguez de Tareygo \u00abA Valente\u00bb(La Valerosa) <\/a><\/h2>\n<h2 style=\"text-align: center;\">Y ahora que conoc\u00e9is esta macabra leyenda. Comenzamos la ruta<\/h2>\n<p style=\"text-align: center;\">El punto de inicio de esta ruta cuenta con un gran parking, restaurante\u00a0 y servicios<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcb3160e4.jpg\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Muy cerquita comienza la ruta<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcb44d277.jpg\" alt=\"\" width=\"433\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">En realidad desde este punto parten dos rutas una <a href=\"https:\/\/es.wikiloc.com\/wikiloc\/view.do?id=14863193\">m\u00e1s complicada<\/a> y circular<\/p>\n<p style=\"text-align: center;\"><strong> no recomendada para ni\u00f1os<\/strong>\u00a0peque\u00f1os de 50 minutos m\u00e1s o menos.<\/p>\n<p><a href=\"https:\/\/es.wikiloc.com\/wikiloc\/view.do?id=14863193\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcb4bf3e8.jpg\" width=\"1172\" height=\"489\" \/><\/a><\/p>\n<p style=\"text-align: center;\">La que hicimos nosotros fue<strong> ida y vuelta<\/strong> por el mismo sitio, un subir y luego bajar de m\u00e1s o menos una hora para 1 kil\u00f3metro que nos dej\u00f3 encantados, la hicimos a paso tranquilo, sacando fotos y par\u00e1ndonos, fu\u00e9 f\u00e1cil y nada peligrosa, elegimos esta forma para subir al castillo que est\u00e1 a una altitud de 1.033 metros.<\/p>\n<h2 style=\"text-align: center;\">Ruta de 1 km- F\u00e1cil- No circular,+- una horita a paso tranquilo \ud83d\ude09<\/h2>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcb5ccef7.jpg\" alt=\"\" width=\"433\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Y a la vuelta a\u00fan tuvimos energ\u00edas para escalarse todo lo que se pudo<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcb67f210.jpg\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Pero cuando ya no puedes m\u00e1s, lo mejor es descansar para cargar pilas,<\/p>\n<p style=\"text-align: center;\">ser competitivo, cansa<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcb7d1c80.jpg\" alt=\"\" width=\"433\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Y vuelta a empezar<\/p>\n<p style=\"text-align: center;\">nunca debemos darnos por vencido, la vida nos ense\u00f1a a intentarlo una y otra vez porque<\/p>\n<p style=\"text-align: center;\"><em>\u201cLa fuerza no viene de la capacidad corporal, sino de la voluntad del alma\u201d.\u00a0<strong>Gandhi<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcb958bed.jpg\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a>\u201cSi quer\u00e9is igualar a muchos, procura\u00a0<strong>superar<\/strong>\u00a0a todos en pureza de conducta y buenas formas\u201d. <strong><em>Lord Chesterfield<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Una RUTA QUE <a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/\">NOS HA ENCANTADO<\/a><\/strong><\/p>\n<h1><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcbb0b898.jpg\" alt=\"\" width=\"769\" height=\"769\" \/><\/a><\/h1>\n<p style=\"text-align: center;\">Se nos abrieron las puertas a un lugar M\u00e1gico<\/p>\n<h1><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcbc893e3.jpg\" alt=\"\" width=\"1153\" height=\"769\" \/><\/a><\/h1>\n<p style=\"text-align: center;\">Y lo conquistamos a nuestra manera \ud83d\ude09<\/p>\n<h1><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcbe2e9e1.jpg\" alt=\"\" width=\"1153\" height=\"769\" \/><\/a><\/h1>\n<h1 style=\"text-align: center;\">RETO<\/h1>\n<p style=\"text-align: center;\">Buscar en el interior <a href=\"https:\/\/es.wikipedia.org\/wiki\/Aljibe\">el Aljibe<\/a><\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcbf81ed8.jpg\" width=\"1153\" height=\"769\" \/><\/a><\/p>\n<h1 style=\"text-align: center;\">RETO retentiva<\/h1>\n<p style=\"text-align: center;\">Recordaremos la leyenda una vez que\u00a0continuemos el viaje ya en el coche<\/p>\n<p style=\"text-align: center;\">\u00bfSe acordar\u00e1n del nombre de la guerra ? vamos hilando, dando pistas..<\/p>\n<p style=\"text-align: center;\">\u00bfCu\u00e1les eran los bandos, \u00f3rdenes y como se llamaban?<\/p>\n<p style=\"text-align: center;\">\u00bfC\u00f3mo se llamaba el hijo peque\u00f1o de Do\u00f1a Sancha? \u00bfy el mayor?<\/p>\n<p style=\"text-align: center;\">Recuerda que la retentiva es la capacidad o facultad de memorizar cosas o acordarse de ellas y como todo en la vida ha de ejercitarse, no fuerces su aprendizaje o este juego \u00abdel recuerda\u00bb ser\u00e1 para ellos una pesadilla.<\/p>\n<p style=\"text-align: center;\">No se acuerda lo recordamos nosotros,<a href=\"https:\/\/potenciartumemoria.wordpress.com\/2010\/10\/27\/trucos-para-convertir-tu-cerebro-en-una-fuente-de-retentiva-y-recordacion-permanente\/\"> ejercitar su mente es el mejor de los ejercicios.<\/a><\/p>\n<p style=\"text-align: center;\">Adapta las preguntas a sus edades, m\u00e1s dificultad cuando el ni\u00f1o as\u00ed lo requiera<\/p>\n<p style=\"text-align: center;\">-Recordamos Frases\u00a0 de Do\u00f1a Sancha<\/p>\n<p style=\"text-align: center;\">-Partes de este texto narrativo: <strong>planteamiento, nudo y desenlace<\/strong><\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcc3ed450.jpg\" alt=\"\" width=\"1153\" height=\"769\" \/><\/a><\/p>\n<h2 style=\"text-align: center;\">Seguimos el viaje?????<\/h2>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/puente-molino-assureira-ponte-sao-bras\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcc5da2fd.jpg\" alt=\"\" width=\"433\" height=\"769\" \/><\/a><\/p>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/puente-molino-assureira-ponte-sao-bras\/\">Ponte de Assueira<\/a><\/h2>\n<blockquote class=\"wp-embedded-content\" data-secret=\"SmYNd8u2To\"><p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/puente-molino-assureira-ponte-sao-bras\/\">Puente y molino de Assureira &#8211; Ponte de S\u00e3o Br\u00e1s<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abPuente y molino de Assureira &#8211; Ponte de S\u00e3o Br\u00e1s\u00bb \u2014 Galicia M\u00e1xica | Algo m\u00e1s que ver en Galicia\" src=\"https:\/\/www.galiciamaxica.eu\/portugal\/puente-molino-assureira-ponte-sao-bras\/embed\/#?secret=vHoBPltjdy#?secret=SmYNd8u2To\" data-secret=\"SmYNd8u2To\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p style=\"text-align: center;\">Y seguimos fot\u00e1ndolo todo, todo<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/puente-molino-assureira-ponte-sao-bras\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcc686bed.jpg\" alt=\"\" width=\"433\" height=\"769\" \/><\/a><\/p>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/puente-molino-assureira-ponte-sao-bras\/\">todo!<\/a><\/h2>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/puente-molino-assureira-ponte-sao-bras\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcc85234c.jpg\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Y al lado de este puente a 100 metros est\u00e1 <a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/puente-cava-da-velha-ponte-nova\/\">este otro que os recomiendo visitar\u00a0<\/a><\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/puente-cava-da-velha-ponte-nova\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcca23992.jpg\" width=\"1378\" height=\"919\" \/><\/a><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"PFer4YajX4\"><p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/puente-cava-da-velha-ponte-nova\/\">Puente de A Cava da Velha o Ponte Nova<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abPuente de A Cava da Velha o Ponte Nova\u00bb \u2014 Galicia M\u00e1xica | Algo m\u00e1s que ver en Galicia\" src=\"https:\/\/www.galiciamaxica.eu\/portugal\/puente-cava-da-velha-ponte-nova\/embed\/#?secret=88Aug3fZAN#?secret=PFer4YajX4\" data-secret=\"PFer4YajX4\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<h2><\/h2>\n<h2><\/h2>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/www.galiciamaxica.eu\/\">\u00bfA d\u00f3nde iremos ahora?<\/a><\/h2>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afccb8a322.jpg\" alt=\"\" width=\"433\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">No mires hacia abajo si tienes v\u00e9rtigo<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afccc17627.jpg\" alt=\"\" width=\"359\" height=\"768\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.galiciamaxica.eu\/\">Regresamos otra vez a Galicia<\/a><\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcccdb884.jpg\" alt=\"\" width=\"433\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Pero antes de llegar a <a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/comarca-da-baixa-limia\/entrimo\/\">Entrimo<\/a>, lugar que elegimos para comer.<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/ponte-da-dorna\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afccd8c85c.jpg\" width=\"1378\" height=\"919\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Portugal nos despide con otra de sus muchas joyas<\/p>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/ponte-da-dorna\/\">El Puente de A Dorna en Ger\u00eas<\/a><\/h2>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/ponte-da-dorna\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afccf5e116.jpg\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"bA9xtD7wZo\"><p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/ponte-da-dorna\/\">Ponte da Dorna<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abPonte da Dorna\u00bb \u2014 Galicia M\u00e1xica | Algo m\u00e1s que ver en Galicia\" src=\"https:\/\/www.galiciamaxica.eu\/portugal\/ponte-da-dorna\/embed\/#?secret=2czntoUXhp#?secret=bA9xtD7wZo\" data-secret=\"bA9xtD7wZo\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p style=\"text-align: center;\">Lo fotografiamos desde arriba<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/ponte-da-dorna\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcd06986a.jpg\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Y continuamos el serpenteante camino a nuestra tierra<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcd238189.jpg\" alt=\"\" width=\"433\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Llegamos a <a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/comarca-da-baixa-limia\/entrimo\/\">Ourense<\/a>,<\/p>\n<p style=\"text-align: center;\">ahora toca buscar el lugar d\u00f3nde vamos a\u00a0 comer<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/comarca-da-baixa-limia\/entrimo\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcd2d39a3.jpg\" alt=\"\" width=\"433\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Comentaros que hoy finales de octubre, estamos a 30 grados, es casi noviembre y hace m\u00e1s calor que muchos d\u00edas de verano o eso nos parece.<\/p>\n<p style=\"text-align: center;\">El embalse de Lindoso est\u00e1 as\u00ed de vacio, asusta, en Portugal tambi\u00e9n se nota y mucho la sequ\u00eda que sufrimos tambi\u00e9n en Galicia.<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/comarca-da-baixa-limia\/entrimo\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcd380473.jpg\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Hoy decidimos que tocaba<a href=\"http:\/\/www.galiciamaxica.eu\/mini\/hoy-picnic\/\"> picnic<\/a> sencillo, con este calor apetec\u00eda.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.recetasgratis.net\/Ensalada-pasta-busqCate-1.html\">Hoy pasta fr\u00eda<\/a> y llevamos los condimentos a parte para que cada uno la acompa\u00f1ase con lo que quisiera<\/p>\n<p><a href=\"http:\/\/www.galiciamaxica.eu\/mini\/hoy-picnic\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcd4e3d9e.jpg\" alt=\"\" width=\"769\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Con el calor que hace y lo que comimos apetece una siesta son ya las cuatro y ya v\u00e9is todo lo que hemos visto, un d\u00eda aqu\u00ed da para much\u00edsimo<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/comarca-da-baixa-limia\/entrimo\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcd5cd622.jpg\" alt=\"\" width=\"433\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Hora de partir al siguiente lugar<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/comarca-da-baixa-limia\/entrimo\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcd6a5df1.jpg\" alt=\"\" width=\"1025\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Llegamos a un lugar en <a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/comarca-da-baixa-limia\/lobios\/\">Lobios<\/a> que os va a encantar<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/comarca-da-baixa-limia\/lobios\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/3gL_1LiKdzj2uiOssgGZiyg045eFLTAgkJWou6zL9j_m4K7xyJ41T69Z9DFU5FUnYVHgxpCVKFo0JaQNOIbzJNI2shaFXJ90AvMzFbfgdF1NA6HR4-XqkfbVD8mlzho9-5xp768OUADI8raCxDWTAA2yeeToC2jZ4NnA33-3jZ45Kq_9KW8wiaI4hITp2d1hW-HTXvW6xXD0UoVHbat3yziqrLeO0M8r9O2AxWkbasBDgRirr7zG9olN9cxvfip8taAkiEI_5u6pzO10eCS0oHhAa9IPAAnEk9LgZKV-fEcnoTbRux65taqkwmWcxQPzZ8L8ISrZiyqkJoqbXAw50Gk3LegBhOTXpzPg8NO7FgPyGCaT_tZ6iEb-OmCxqbGoPGsAiR7ZFUE8nojCDNX6cEGLdY5ckF27qabZ43rbr5ER6JL6P4aXxQSmKyGwcD_8n9qTsdxG1vtpknY7JgnXJ9385kr-WfFNe5E81vDD7UcmAA2hEWGM7TiPoaqiKPfVTSNsNfqq5EqqffaRmATMMfjfxGTqLVssbRpxRtLoEaa41pVUk04G37t_AkWK9PLIznlTtJSdggbGIoCJZf9HjNkIqmk3EAxR6A5A1tjYycA=w1368-h769-no\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Un lugar que dispone de amplio parking y \u00e1rea recreativa con mesas<a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/casa-da-escusalla\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/8nqT7OKWnGA87ynA_QI0USv_IdUX6FyT2LYoj28HSJR7p25CJxqXxxhqUXvIO2Tk_VVrG5xO6FCmy478ikQSeoBMYowBkglLhaI2p5vGiDuUkvk6HizLOWyUBlE2Qk-dzH5K-pdyFfcrLUQCQ1k4pAcIrlnF71rXh0srgJWsmM9FkoeChvAAzUYH8VZrDfUsBbhPzq1TwVp15IVr81PxHkuOTdGRwGsAM37jg12LFpWVyxzHwmpKPxecfDmqRSTNCLROdAKgtRtrHKmnYv2JQ61p-GKd5i4kVICYy-gHbBiR5OuyZKLBHENAhZpAcuV7w9PSageuCCLvjAxUtNKwF8pdcwbxVs2SxZKTnzt1aAoNL0AW98M7IspslZeAywRcRE73TBWUG6ZugI5seyLOzwxC90mU3DSUnodylzhz30DOwYD2sxF4YmSYKCRDqgpAVVpR-dV8nTB-a7tN3jMl-KR1ttv5sDK9YGWIYKAW4ZxdjT7OcKQbL9Q-QREhTkg68KN5jkS3koh_BxOxiLI4K1Ek_ibdXI3y3icWJrwLtiUTUdR0G3OH9XqIHsYCBJTQNoZXcTW-33mlkY5ePquBiTqGmb3sZFKEA5Dp-xBkwJ0=s769-no\" alt=\"\" width=\"769\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Esta casa marca el inicio de un agradable sendero a la orilla del r\u00edo Mao en el que se pueden ver varios molinos restaurados.<\/p>\n<p><a href=\"http:\/\/www.queverengalicia.com\/2013\/07\/senderismo-sendeiro-do-rio-mao-baixa.html\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/9087684782_7d3a97b9c9_z.jpg\" width=\"640\" height=\"480\" \/><\/a><\/p>\n<p style=\"text-align: center;\">La senda es circular de unos <strong>4km<\/strong> y su<a href=\"http:\/\/www.queverengalicia.com\/2013\/07\/senderismo-sendeiro-do-rio-mao-baixa.html\"><strong> dificultad es baja<\/strong><\/a> con lo que es apta para todas las edades.<br \/>\n<a href=\"http:\/\/turismourense.com\/senderismo\">RUTA R\u00cdO MAO<\/a><\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/casa-da-escusalla\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/RghGXCFJj23IiqJ37rICaVXvjtjv1HT2hSfWbvXkz71Vp-uh2NanqXTVUOg_AMB1IFEMuO6ODkehwdr4jfK06n74fI2yp7NdTK3vUwdAqD29M3Of7jg5ym41WvYL0YILbZ5mW3ZdW81vEmA6GvSuzhUW_9-IViXE7RggUoa7ukY4oIpliQ1xK4y5_tYTxEHvqDZk6ijyEN3Rx2weP2Jd0c-Gti3fTdn5uV8TqOuRI4fVauh_NPnA2eENiRqQzM6fXM92BaQnipPCe-NIGtm7eMNm7lETVfvoYja9skG9DPiUEyySlE2a_OFPQl0_MKUAElawLNcKh0l4s_bGpACPfsJxW3Qv3uY29cFUma192YA_cOawUMM77V9QYGEptN0yStGVJ89OnPKBm6ZaKGZtl-ahXH_t6CiovgxTygouKUrHNSWvZK35QoOy0PpqAZtXw8yIgednMnqq_RFMW4b4DEb9KsBGKuxp5oJy99XkWwz4ysNdckV3w-D3OWlf-fhSSHn1bJ4y8TPJtM9UzN7xohPhEuxpkn850OGtv58hXmiPUWxM3Jv9gC70pLvdKl1rMFjDOVm5-lt_D031tYqwrlV94QpS0ACA1dGzE0qvSpc=w1368-h769-no\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Pero la dejaremos para otro d\u00eda porque lo que vinimos a descubrir es una casa muy famosa \u00abA Escusalla\u00bb, a la que Cuarto Milenio dedic\u00f3 uno de sus programas \u201cLA CAPILLA DEL MONJE JOROBADO\u201d, (entra en el enlace descubrir\u00e1s su historia a partir del minuto 44).<\/p>\n<p style=\"text-align: center;\">Esta casa esconde las historias m\u00e1s terror\u00edficas y como se acerca <strong>La fiesta de Difuntos<\/strong> decidimos venir a pasar un poco de miedo y vivir un poco antes el <a href=\"https:\/\/es.wikipedia.org\/wiki\/Samhain\">Samhain<\/a> Celta, Samain o Halloween galego.<\/p>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/casa-da-escusalla\/\">A ESCUSALLA<\/a><\/h2>\n<blockquote class=\"wp-embedded-content\" data-secret=\"mMumfRmgKD\"><p><a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/casa-da-escusalla\/\">Casa da Escusalla<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abCasa da Escusalla\u00bb \u2014 Galicia M\u00e1xica | Algo m\u00e1s que ver en Galicia\" src=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/casa-da-escusalla\/embed\/#?secret=bZTnUMerXl#?secret=mMumfRmgKD\" data-secret=\"mMumfRmgKD\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p style=\"text-align: center;\">Es una casa en ruinas situada en\u00a0 una aldea perteneciente al ayuntamiento de Lobios,\u00a0rodeada de leyendas y misterios.<\/p>\n<p style=\"text-align: center;\">Cuentan que durante las noches de luna llena, se ve un fraile paseando por la casa y orando en las diferentes estancias, un fraile jorobado denominado \u00abMarrequi\u00f1o\u00bb que se aparece con dos damas vestidas de blanco y que invita a todos los que pasean por all\u00ed que no vuelvan.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afcda348a7.gif\" width=\"426\" height=\"202\" \/><\/p>\n<p>Tambi\u00e9n dicen que durante las noches que NO hay luna llena, vagan diversas \u00e1nimas,\u00a0 se dice que son de jornaleros portugueses que el p\u00e1rroco contrat\u00f3 para diversas labores y que para no gastar su dinero los mat\u00f3 y los enterr\u00f3, unos dicen que en el jard\u00edn de esta edificaci\u00f3n.<\/p>\n<p style=\"text-align: center;\">Nosotros como la visitamos por la tarde, tuvimos suerte porque no aparecieron,<\/p>\n<p style=\"text-align: center;\">aunque la verdad\u00a0 Tea estuvo algo extra\u00f1a \ud83d\ude09 no se si los ver\u00eda traspasando las paredes.<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/casa-da-escusalla\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/iWqxIJaYB2jvsGO2MCRmUzAHxOt3eoK1teU6trOW_LSu5Z3Tz12OluaVdGdn1-CnKTSe0RvibXSXM7C1Yn67-LzZb2Q85Iqs7e1uo8PzC4W55psBh3HaaPknx7WzgltIm0_9u5ZwxuLo8pvBY9hDnOL2C_w0aeYFypbjblZaRoWC_g7eW6PP-X7c5SJnO3IPZ5zFCcEPW0lCCzie2p9Ks3gabO7o9Wibd_Vd3oVTE7xzGLI5HdII8RBPzchYGanh6DVA7hpoQ_flLcu1dvGjYjLek_vY-UlVE-qq1ANRTVeKIaX1cJLpjVPZj7RaoNg3Ta2-uzg37JPDLprugpNgnz8s_JOrqHRLoic5Xw7WGb2NqhoSEJQH_W2jG8udHE9PCml1fFPpzbGkmWmsMQ4AHRFNj20KfPZAeEmcrXOWbADSqa7c3yXL-UVZWZtYT1zeat9HDI9h8hY--x5FnSkoOEaWN3mflXHJ8all0KsHDsl-Ycmz-knJTwTdHFuY1nuA0W59P-AMQvNXqHWBlH08RIzbkSoCzEAWlEUONpCa-tE5ynqImWnN602dvdl06u1hdQEiFu3z3TA8yQHbMCBLlPAmi11rH6YXjLtYyGL94Sk=s769-no\" alt=\"\" width=\"769\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">No hay nada que indique que all\u00ed se cometieron asesinatos o que existan cad\u00e1veres en el lugar; pero ya sabes las leyendas tienen otras funciones mantener alejados a los ladrones, pod\u00eda bien ser tambi\u00e9n su finalidad o evitar que corri\u00e9semos peligro por las noches, habr\u00eda que preguntarle a las piedras de sus muros porque si le pregunt\u00e1semos a los vecinos se nos quitar\u00edan mucho las ganas de descubrirla.<\/p>\n<p>Cuentan que su \u00faltimo habitante fue el T\u00edo Roque, un polic\u00eda fiscal portugu\u00e9s, que seg\u00fan dicen, alguna noche vio un fraile con dos mujeres y escuchaba sonidos de animales en la casa cuando \u00e9l no ten\u00eda ninguno. Tras la muerte del T\u00edo Roque, no hubo m\u00e1s residentes en la casa, tan s\u00f3lo unos vagabundos portugueses que s\u00f3lo se refugiaron un d\u00eda y no repitieron ante las apariciones que dijeron soportar durante toda la noche.<\/p>\n<p style=\"text-align: center;\"><iframe src=\"https:\/\/www.youtube.com\/embed\/7IoOtr-3w6E\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"text-align: center;\"><a class=\"yt-simple-endpoint style-scope yt-formatted-string\" href=\"https:\/\/www.youtube.com\/channel\/UCme4o7qH4F8L4MzbSRNuWiQ\">Manuel Baptista<\/a><\/p>\n<p style=\"text-align: center;\">Ya desde fuera nos impact\u00f3 lo grande que resultaba, la verdad vimos videos antes de visitarla y hab\u00edamos pensado que se encontraba en medio de alg\u00fan sendero perdido y que era bastante m\u00e1s peque\u00f1a, nada mejor que descubrirla en situ que no te cuenten los viajes ya sabes, v\u00edvelos y cu\u00e9ntalos mejor t\u00fa.<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/casa-da-escusalla\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/pD-y6r9K-7Xks8gRVlSOeCV9rs9uAKPbWTj3CsQLHf_1FxhU3tcGDxOj8rf8cGMBJ7gc392r-D8u-MNVeozD92MhlCe5N6Kzzb5PEtFQ1lu8Qf4EXiXaMdiOzGJjwsb7SLhc3ZMX24CwSak3Co6RzKdcnGOzJcQcB6GhSs3T374vhgJ-Tcs05eQ5vdK0SUCD1aufzjNfl_3vZ4OzAY3rUpmmlS_nS8_nsBFNGX9reHuAPFlRuTya57wT3RPXO5cx8a_Orh_JdrEwSkBu138vGUYYAVLvxzIqRGgIudr-1mgWRBLvNSEb7oFx9s8103Le-DAFACjGty4OySDSXiJ6wjrXfQ65CHFCsnW7EbFI3PbgigTvGc6-RjZYyXN8QAa1ppMPcJ5xWZZznKQqumhMW4ZGAQ5pxsKakU9h5PrCwvAc-h8cP0rMCT2zCpUcmTpv6UPKJtEDFBbIeQLiE7dT6qCMvzxxoFZtA0973ZO2PIaonEoJW8fQt4IQZwQfhB5HCx9JHt1TNdyuJQCMMrYN-mvUxmR_ffPupQFlQktmY65VWx6IIA69CGLkq8ZjURdNPUm5FuBHxs5Atrl0_4Z8xI_21SO2PV23OQl7Cmy7zVk=w433-h769-no\" alt=\"\" width=\"433\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">A esta casa le dedicamos una entrada porque cuenta con muchas leyendas e historias que seguro que os gustar\u00e1 conocer.<\/p>\n<p style=\"text-align: center;\">La ermita nos encant\u00f3 lejos de asustarnos.<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/casa-da-escusalla\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/n00xvhBUbhBLpQ7wP9eO5cOt36NcoLzpU0YtX1RdtlLVi_EyRjMh3c9RoOFCsHY_7WzdPAbQvd-P7lnvL7Umz_ZWu9h8EZpCqpLGCmySW6IEuMakwP7L1LbvVPuJNPCJjjVG5uOuDOA42VuQZJSTANv0YPDfe5u2GV43lImanPGwRiH5hTIUV5GHJb2-koWUsyKxmzDUna6qJ5LChxwwgEo5vL-nAKKe6vVZ1xPcxK5cN6kllQWXqGXTK92IiR_w0wLdj5gWWUlHQjkT3OGVyU1eXMQl3r91JwO89-I5thYbmp2iIo0gaHT9s2yPuk8gyrDi-tH4l7s9P7T77I5eHeaoSJIWqvQ13FXf388xAsi2cvWXA0LIIV9dIpiYHQDI-Gfon8KS2n0C_ANT_aePWXJpbYANiQhsPcEgkDnbafSUV6mgcU9DKIU_63cG4rp3zrOU-OrvUkP3KtxsNJD94ol1V4_YChqT1WtagfDWe1STwlHBWN9OZoQ0My2x2bDXrjXb-Ze3nVlcWAJHtGJk6abfIuHZHAZCnVUeEnkLtcvnCIr-beRYhLmotcbFDvvgzkoW8DL9eKtH-6ALMjFVRRk5PqKrMka2yxaDlZq9FXI=s769-no\" alt=\"\" width=\"769\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Descubrimos cada una de sus estancias y los m\u00e1s observadores nos preguntaron el por qu\u00e9 de la columna desplazada, no supimos darles explicaci\u00f3n y si mil y una conjeturas, alguna ser\u00e1 la correcta, esperemos XD .<\/p>\n<p style=\"text-align: center;\">No creemos que fuese el \u00abMonje Jorobado\u00bb pero todo es posible en Galicia, \ud83d\ude09 y no descartamos esa opci\u00f3n<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/casa-da-escusalla\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/xeuwMjsokcTwQfqxPBj1FECjDr-Dd1zjFCyNQgdVqCe9FY3d-GZYwJv1nXHWQbeQZA3wsC8jBc-SfY7UBkowV6X2Oi1liEnOW47_lVnXNU51JOzgjV3t7_DCkCBCGh7bp0ZnZCVRl2cmZO8pLsQAD4bBu081gW40bVk1LeXGobLuZUxYULqC8udVuJP9Vf22uNSLWzjW0TE4GaHOvpyfNPTe7BF_2YVczaR6q0J4jw-IqCZFzGHIuH-qTujm2avv-yMuCjF1GMUyFrGERiia57b7ay-kq5LgZuTj46GRZHJmB6su-CR50xGPgKud28gKOkkE9uSjOssIYQ14a4si27j5E5YMNiAsnCSOyId1qKh9IpkYC3bUxW0-orhmYtvYeTB3xF76LGCX-2r36-sNultSdXAl75amenfI8FK8NKnbFpFZs3JiHY16xufrY-kJ9I9ECWtEbkOz0_lOQd0ff37o8vd8CnIryNfhOFetYbGZCCbIdMFhmpZS4H5hlKzX8UUF51dUpB9X0MOes1LQJrk0TgDVXurBLmdoGzV1rV5S_sfJaSgCJXz-9Wp2DqXTGFb1ksA_2VfsOtR3utBngL8P1gwNJ2oQHRYOkJjBUnY=w433-h769-no\" alt=\"\" width=\"433\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Un lugar que da mucho juego a <a href=\"http:\/\/vialethes.es\/escusalla-casa-encantada-xures\">historias <\/a>sin final<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/casa-da-escusalla\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/kOMLAlG_f3XdGlNqIxZaIs4yKkryFxYSLAAOSMOzyiPO8vxgdNSGHF6EwKZpMrKoHRVsvFwPUgHHS2dY7ylhsIzFluPPaNxABMzfXMGtXJlfQ5bBZdN5A2phpX9s7QVcxxHMcEoFBzZbgFOZ_K9FZCL0YSgurNkB3PnXjfSlgywsBGnY-kDro6GeO4uhJs8pvXKLSJ_wMoSNRqPgwMjVxwUPXUqdzX6FzQJ5HsnoakgmaEl5WPljoKwfddzTOP2oUzgHMH6UH51glWGqh7J6drPUbSm5FPREz9btsQjvN5vhl2QbZueN0NTQeJulSX48euZ0lOZJfU38cJ20mJnHJJgO9CVN6VYUg09DEbbrHKkXVjcTBKATaE5bAuwZPJUnCb6_geIRjEUnjqOlP2_HuX4oar4JZZATZRuZD6VuAcmOyPDIpwUwQUL7kkWnXlSzzFliYvTD0rtHM-p-7ZEXeEvfkO87ZVHvXioXDj6-mt5-amMtgIC7Jf1W99vv6ia8kjBrNkjuJUDDGVy73hapygE2QVIETg1v0WFUZsfmX59__AmCrOb9SlsoE4l_jHS6eflHIDn9gryA3UpdafYd7zbVaFQDNqvUm0Xh2r4Aqa4=w1368-h769-no\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">O con un final terror\u00edfico<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/casa-da-escusalla\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/EuanH6GrB6_zlvgp7T3VfmyqmkeRK7LwHmmUQJBMTUct43_EyMHfeE1WogIKrRZKjUrmj6CD14ZrkJ_9wfxkzJF0eJW_nOEj3YqaPJIDwO85FGdZSEAV7mrmMPUrIuLfOdtrh-cQYUDz85nMHM_cMxOz-LAYHvSr0JhBvOjyxb_N1xHQ97LvtfdfxmG2gm6tdAXbwUy7x7vlZRhNGAPL5Uc0ekzD4crklFXbqn4Vwp62p4g-SviGML4fhUq32NpigocH9lWjo2QFKVu5z05c-rAlMVavqP_QzGomM9wn841jDCkuJY9YR0AtFAWQxTXTkA6QxPjhXoQ-EF2MuFSQGn5BT771C7KryCgvMtg6PhM4Qk80zVfCxQEzZRudcdcij4EDWFtzO_JUZkdPWRDV9SBU5aVEwjgo8C79G25Rn5ilWmiTmWC9Mz-jMp5M7sQPVqAnxPiikL8wQKm1BvjyKXMTzfmzWenzaNBiOVIpR73SH0GSdk4fvG-ctMP_68CcBxUfL9hBk4ibGPO_XjU6aLV5-Am2kbJagBT3d8_0BD6ds3VKCJ-iCBnZRfBLEbD6DXPcBRyjVfb_omwcsAb3tE2waojbL3nF_OGUzW742co=w1368-h769-no\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Lo que est\u00e1 claro que la naturaleza se ha adue\u00f1ado de todo, ella no teme ni a los fantasmas y ocupa el que fuera antes su lugar.<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/casa-da-escusalla\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/IVmxn-bKV4fgLVUNYgIP2Ss4iQo7PxbXmFkal2yZxxY_zNE8VtQLM2R-0RlC4fb-G8LxBHWTXOML8-tRMQgnu3OuXpettPdX-1gAkYimhbG3dJADdX4MxqKuhH2m8tmLw9K6wWY8ALvqspKAeLZgu2gtup9y25cBUdNFGEjJpzSwDOcb8_VMrYbVZXVCO5t9mYs99TuYvrSfak4W_1Ah6tp-REVtS65hRh87pSDFud765d0aOjlnxCuPmMI7IscbKlNtGsPfgP6cy01ovCkbfQCxhMP1DtJx5HTahsCMNRPrz8LYy-ZkC6P2AQgQns-G63oBC6s_x3g1fivoPjOqGsEAapIo27IARcOerap1ecr0tTNDz5oEt2A3vglu2_JB-qyzY9oItbXEKJ4bXAV92FvODbADP5h-YY01bDRF5whwkyCe8xesUE1-zlTxtMcreOU2aGV23TslWV-8Yl9Ise0Ju0XRABATC1hGjTIVCqA0w6DS-SYo_Qr47w6uK7taCsdpJI0_iVOk224eAfsGFCIppSWj12o4SkAWFmgkvjKI_7ZRgy1qV1kuo32wfuDnNCD9HblEKYRg_IgCFfnEebvFcEiKN6wDXC06PadBmMY=s769-no\" alt=\"\" width=\"769\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Nosotros no hemos visto fantasmas igual no era la hora adecuada para hacerlo, ha de ser bien entrada la noche, probablemente en la hora m\u00e1gica, esa que abre las puertas del m\u00e1s all\u00e1.<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/casa-da-escusalla\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/-ZCf-URaiA_tGqOobJDgzJZPlUfpjAXzM5F0R_NEsAhH_lJOvc2xhmkHHdI2uIz77ec_U0YX_5GYPG9nagWlmpdgxAGDexnSA7N4YjAKBaTdZRCdUb7181hswj6iaGAXq5Y5ayIP4ZN67lmP8c4Fzn4lAkKH0Jlm65iwkAtmCJexQLOg2MgVkRQyG9WDYmb69d_eF5feBhmXPNCk3rSMk7V_92VlYPiH0pTiHygebCpp1MOeuv4vSf3KPbpKYPsqLz-oIbTdeTWwJRJHp9nbAbJyolQ3lOCEeyO1ldCx-I6zdgNE-otT4usGQqtKaBmc_Ungd7NADTpCv7BMKtWoeM51cvOF9-u7dmC9b7syF67IB-9WrooEzfyx80BGNTey0V40Wz1w2sUFigfAIMHX7gyjBDPRm0e8L_-lzj6Qpab2Tq3u-f9Ecefefv2GEHIpXhcUd3ILL106hPu11b5Y2Ce4uL65vIB_ONQUn5rqkuM-MsvRiUekAhUv-mlF8uZ48PPk2v5A5vBGmWkb8gbOplSOY-Ad4M2PHCR-_OJHvq-4DshTCTMVqnc81O5WdnYEWNRDM8zb8LWhNLD9bPL-Ygt4unYASXd-ZXT0Yq622n8=w1368-h769-no\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<h1 style=\"text-align: center;\">RETO<\/h1>\n<p style=\"text-align: center;\">Encuentra la Cruz de Malta<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/vialethes.es\/escusalla-casa-encantada-xures\">Nos sorprendi\u00f3 <\/a><\/p>\n<ul>\n<li>encontrar la <a href=\"https:\/\/es.wikipedia.org\/wiki\/Cruz_de_Malta\">Cruz de Malta\u00a0<\/a>o tambi\u00e9n conocida como La cruz de San Juan, un s\u00edmbolo hospitalario\u00a0en este lugar, tambi\u00e9n se dice que fu\u00e9 sede de la inquisici\u00f3n \u00abdicen\u00bb porque el que la construy\u00f3 pertenec\u00eda a la inquisici\u00f3n, Jos\u00e9 Mart\u00ednez y Parga.<\/li>\n<li>y que el lugar se denominase \u00ab<strong>Sacellum D. Joseph\u00bb<\/strong>\u00a0Sacellum significa\u00a0santuario romano,\u00bblugar sagrado\u00bb, los romanos utilizaban esta palabra para los templos dedicados a una divinidad, si yo tuviese que elegir para aqu\u00ed una divinidad, elegir\u00eda a Cloacina\u00a0\u00abla que purifica\u00bb igual no os suena tanto como Venus pero es la misma en etrusco, la verdad Joseph me suena un poco ingl\u00e9s lo que me descoloca mucho, toca seguir investigando porque en los viajes aprendemos todos y d\u00e1ndole vueltas, \u00bfqu\u00e9 significar\u00e1 Sacellum en ingl\u00e9s? pues significa \u00abtumba dentro de una iglesia\u00bb lo que aprendemos pero ahora lo que me descoloca es esa \u00abD.\u00bb&#8230; habr\u00e1 que investigar mucho m\u00e1s he visto otra cruz que me ha dejado muy asombrada.<\/li>\n<\/ul>\n<p><a href=\"http:\/\/vialethes.es\/escusalla-casa-encantada-xures\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/Sacellum_Escusalla_eirasenda_blogspot.jpg\" width=\"717\" height=\"336\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Este lugar lejos de aterrorizarnos nos di\u00f3 mucha tranquilidad,<\/p>\n<p style=\"text-align: center;\">es que mam\u00e1 me dijo una vocecita ya aqu\u00ed\u00a0<strong>\u00abson bueni\u00f1os\u00bb <\/strong>y yo me la creo.<\/p>\n<p style=\"text-align: center;\">Aunque no te conf\u00edes porque pueden aparecer fantasmas en cualquier momento,\u00a0no baj\u00e9is la guardia.<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/galicia\/ourense\/casa-da-escusalla\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/cfViOaAU1cmuiXjl63HHUnk4PUSPdgSpZ39pxeSUaTQ-jZjnpu5V_lfLK3OxrNItDxEcZOl_PzvvMTnLdoAkV3OFx_Jijj46nshHgu_Ah6e-cX5KyeqNT9dKrzMcdbLJ6yz2sB83sCyvShuybPfIOuzWrVfCrDc5r_PK9hSPrKGJ8_zimO16OuM3FqUPgRG6tBxFWxpP-v7lznfnXgki8G1zWM77tv_NGQmYY7kXY4nLlHZBuwgymXMLoaAEM-qd8wtULgzoH70pL4cYLAGeCC4VIL7Lv4Hb9h1kGXrXyDrPLYCRQ4zUpERwX1tXtLIrAioXwftkJ96_HLsbGmUK65C779QY1u_2xDVsa8-pY8sUOu2LlAz2FxVTBQQ38UQH6_TrSSNUt6HGKyg74qZxOYakQzF74mO6KQ0Tm4kn5tibF4jm3d4ur2x5nPabny1KTzpsf-5ac-MYkBKiGRXn7fcEWaTMYHqlG4IQ910jhwGMXzTY3yMr40hzuGevH315IBNHKsTQ-Wz1nCGZOz6imKIG8mBZJVX43Eih8siqmD8iEjbeDyxtFoJebsie1s43OdQ038LFF2d7fSj_4ENDZy_FdTpOKXcHLmtsmyQwqv8=w433-h769-no\" alt=\"\" width=\"433\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Ahora nos toca conquistar un Castillo y para hacerlo, tenemos que volver a Portugal<\/p>\n<h2 style=\"text-align: center;\">Nos vamos al <a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castillo-lindoso\/\">CASTILLO DE LINDOSO<\/a><\/h2>\n<blockquote class=\"wp-embedded-content\" data-secret=\"fFoCtUAzMk\"><p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castillo-lindoso\/\">Castillo de Lindoso<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abCastillo de Lindoso\u00bb \u2014 Galicia M\u00e1xica | Algo m\u00e1s que ver en Galicia\" src=\"https:\/\/www.galiciamaxica.eu\/portugal\/castillo-lindoso\/embed\/#?secret=z5oB1qb507#?secret=fFoCtUAzMk\" data-secret=\"fFoCtUAzMk\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castillo-lindoso\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/iDTwdoEM-6mcjXTplYmlo9jQQc1vk6I1Kqjrvfql8kqFl4wMJvm2MFDW_GV5BmomgCXxJgp0MjyvciQRfPcMYsBOyHLofR4FKqAVbsT2p02U_2Gmh_VOhqofJW4HTGFmFMaVdtyg48u7dYetPosOkKIaCnoixwTx6XDzJQAYGQiPoOe6-EyftU1XksP5E_J11AOGqW4WD8_t3exEb6xbu3oiLBg4eRCY0MAEKOIsyDs72F4r2ReCjMLqRGvrYTjy0BnLI0SUaR0ITmtWF_1EORAm21yTSXxMpqvL_TAoJs62bY1GXzA56ZgbF4H_BquOsS7tohaHkX_Fu1bE4dX-rO-V_0MlDDKu0uTHG-q8ZN6SkHinrq5ij4sYEoqlfSF3pvM6GmRU7-3arorNG8LZhV4CZfxfGrsujffnJQ_hs3DoKk_ZLWOev5QagmZP9mgzD3l3JdnQVb5pdDeQLLlsDfm7YMxUbIBcQ3Unj3qKvsl1lK2dfWw5OChLe2nwjzJWt_7RYl6u_iik4L7au2FAXlfmpbjxTXnRq4vsWd9V0Ogz87tSs2EajIQcxN3jtDRLuinLFnTNZyoY0zxqF9QoMiL-Gv6UVQlq8Ue0iCTPOEY=w433-h769-no\" alt=\"\" width=\"433\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Para descubrir una joya patrimonial que encierra en su interior un precioso centro interpretativo,<\/p>\n<p style=\"text-align: center;\">un museo que os recomendamos visitar<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castillo-lindoso\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/D9F6h_DDWOyzrGQXPnYI69eLg2YIVucV2LleC7wlscsDZYUB0yFlYJUsvb6jaCAzjNsKkNX2yp64ZZ2fneS_FLMMtBrjFo4pK0HqUJ0ZygaQs7sKhHBzTx5NWFIIrWJfkkHNvMZ1vDjAJdmu_34vCUDxHMljXaox_10pMgGNyNaA3UPmijaUfVm3vdKip9s9PWvz9rlo66bo4QhiPh_6R24LvDrjJcfwY0ufhdNcvqGqEdpAffFTzpRc-ayOo3mmIq0ZCz8nUiZM9-EWvXzqroJ3p72MsKl4O3Ezzf2IbpAtxym8gXu9PvqAHlhHz21-ABFA__-JQvxjTyUEUzPoXr0IN_8M9fx8bakqkptwfBIFPbjItSFrAwtIeuP-IlqFYP9h6ua8ET_nR79Ji-dj7547-hc96Q6diOo1UbVC6TA3OuJlxTRhZuPTDzCAV77ntARzLAeJZenGwY9E2p2ZTr5Q8fz5XwRRT4EhQEDRUjm9nRkotLo0jqNOWjowHAW-GUBl9NXPAyDs9qp5WaxgNbc7-WV7zT_wFPyMaAt1pEqqbv37tQ3QSr440GdGkZvaN5uwOxOO_TmhsGU5BANT1x3pojtXJtFkzr12CpEIOBQ=s769-no\" alt=\"\" width=\"769\" height=\"769\" \/><\/a><\/p>\n<p><a href=\"http:\/\/asenhoradomonte.com\/tag\/lenda-do-castelo-de-lindoso\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/lh3.googleusercontent.com\/AiWg3sMx7dGL6oE23NkbfHmBSM2raLYXGGLB8G49yMA48d9Pble_wJcAuBHfnlogiUBlR4Bqpgz2R7tvWgeWvD9HnCbYcwcPsunpd8VQ1QALIgNj-ij87qDhJyCaxmx3SY81tP0fdkJ1vtiR0yUV6fmeZyixT9sUu1-bZGSlrLjprLVtcRQ3xFGTDAGug8ZuXjFhTPXjQ9oStUTRICr-qUvT76RN3klNzjHQjPT1t_DMccAbToSbp8L5ApKDVbSfonQHDgIxTREAGCeKBfzkmTF_6cAEzOJt304QZmbYntyDODQdoQScXdmCBxlp_CoEs_yoOHX16_rWGjTP9FM4D1NWdSxS2RzHPnq3BaTXuz09juYIImmTHMZ3WFeoN_vRPSc7sLzqsWCsJXLhgpeDL7xdbMj9I36ig3WsfK582OvyJ_aEaaW8X42zmYck9JCBuJxIddXpGvXjLpvqGG2h_Cr-ysSRRULR-PYA8AlXv5rUG9Us4_rzAbtqoPf_Ipi5zEjzJSiMm88AMEFhd-EYzWvUZpRmTi2Dc5Q6gzhh0gRPmjHPId0yNtJq8bF9mPYxsV1oUHTJOibv2V7sSs8_OnohKp5Sfo6JsfCPJKEB0P8=w841-h524-no\" width=\"841\" height=\"524\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Cuentan que el nombre de Lindoso surge de esta preciosa leyenda, pero tambi\u00e9n de la palabra latina\u00a0\u00abLimitosum\u00bb, que em portugu\u00eas\u00a0<em>significa<\/em>\u00a0\u00abl\u00edmite\u00bb tambi\u00e9n significa <strong>cementerio<\/strong><\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castillo-lindoso\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afce2b3a5f.gif\" alt=\"\" width=\"434\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Entramos en el recinto<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castillo-lindoso\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/3bVTdXbmlncaP9KQbGdqEmUdQjr8V0fx1E0mATScqAcAWSTQqq71OsaoRYLRVQ0BkkmRl2Gook-sH7ewhipfW2w_u5TynANtAEQQyNU6x4VAOr6H8IIaVrVVjybmXJwHu1Ef8wzpeCNkK0UOwmQpvTiEYlkFIVjrUdmABmMf8y63DyZoUrvuGBPwwmTVhNKvt2e-pk_4yBRJN2QeZVaEF64EU6Xy0f9SzkwDZfLrfpURdZk4ILptcyoBmZxBOubjS3bTC8TLRwgeUU06uAr_DZOZ8omtwI7yQBAR2rris78ksCYX3VDIJgYXTMQJzwVn-Ge8ZC4bVdKQTjEnKHx4EPVsIwBFIjyAUxRSda5-0yk0flHWygHGtTDBU7rohRLySVfRXd9RsflYcyABVLqyoHD1CxSWqpBoyr8pwrOG81WlaD1z601wk0sDNNeEaOf-gM74zEL1alkGRGWGSdFyWOGOeadm6ODEYEcBmPaZv1uT6mOEYN14xz_HSL5wjSs-JJUs-qbeujbdEzy0m3PD8el66p06EvLOTofDpuUgWZOubCMAnWroDdJsSL02Tl3LNw8DxkYi1DCZi2grVsn7bD9FOVSwBYFv4pUKluGFAP8=s769-no\" alt=\"\" width=\"769\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Caminar por los muros de la fortaleza nos da una perspectiva de donde se localiza este bien patrimonio tan especial<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castillo-lindoso\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/UXGoyuGzAIFSM6XBpnItUisSQxLVrttZOCVMPiWHGD2NmNhLUUPteqpw0Z_HTkeGg7w2sIDqpTgSedK81nbNnus2PoCbwwWDFJHJESCecNA7SBJ3mpy8NXkNm_57Id3QDGZ3k0K8br26vN12-MiwCp-lintmpIB6PiK6PBTxnaSfLeFNxZ9iRPFQoXmB4Z72rI3sBgiqi2u9lYuisHkVOxEPbMLMvdPYkRJe9sOUeh6eEwIEnLblYv3Iw6n2sra6EC3RIPqrbN9pTLDXsifyKp4V6CF02VZ3s4tqzFxWg8aYw_LdwM2PjKQiiWfSuBQES8Zkt0B5YyrGzMfjZP9Q473i0EMUz3Swfdlx8CDh_Lg1gEfcYsono1zYdqJOrwgb8jYQ7WD9fIkxnWGpv1fWTJZvZ6J1GBpyC18kA3wtW_2bTGHaPmVDl7aqJ4wtNAHd4MbW814knPM_NL3xWHCwwEX6i1fmErOpYU3l1TQqqLFrU21AYtB8ul2KxMCjLgvVBzDQ05W-6FTG-Sh5qISyg-7_5smg_RwjhrXDSeBTUK1KHwCrenSc0XmjI0EjRpcj5PT_s7sXHKkHHkolc43RQp9vjQfmDptzzxOhZiw8EIM=s769-no\" alt=\"\" width=\"769\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Y contemplarlo todo desde arriba nos encanta, comentaros que cre\u00edamos que la Torre era el mirador nos equivocamos.<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castillo-lindoso\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/S7mRf2gnv90BAnjiudSrT-jFU-HQGdwqQyVKEd2RjJ86bIb7dygPGmJJJXcjLJc0DfHXQqLw7CoBPJ1buD-T9tbE9iVdLmeZsokW8yRO1cHa5lC7igl5skr-26mGyRCeXDCbal_q8YeBdrn8yvrJE47lzShQjNgkZcgMGADh9xESJjYwV-w-e_GT5r9rZm81dA-RzAh1gCI67KKB-r3-B_GsOy5XiJ0njVK0k9SOmaG5GcOxkMc1plIH_NCkpDblVKh0-yAK7z6v33-xVqDnXQWdkCapaVNghfKiWQs5pNLfqG3_DlNsp5ordIliv9elPE69WIafY52GJROwsHV3GDiuEnCcUxzPFNoVBbUjTP7QW8-GbD13bxASHizQjs1Xd4drUm8cwiyhZxs3Acr3v8SA0yV6N0MvSps5qvHPpR3aKgl1BxnDHDZLrBNmAYfWCOOepyzmxbSlPqG-4es1L0zZdvQyjKeqrLs5Skz561kjB8UlFjtc2SJEbVG_mPSJUBVLWuXuMRrom1GLW1qGKJjvpyl8pZ4aKnmfnmWDYa80qWoV0Y3rGxB6UrZDFHBj4_y7SYr6t_IDOK29IUSWbCwtyr-B7uCJganE5IpvlkU=w1368-h769-no\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Apreciamos los preciosos \u00ab<a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/horreos-de-lindoso\/\">espigueiros\u00bb, h\u00f3rreos <\/a>en castellano a sus p\u00edes,<\/p>\n<p style=\"text-align: center;\">un conjunto digno de visitar tambi\u00e9n desde abajo el conjunto cuenta 64 espigueiros<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/ciudad-dormida.blogspot.com.es\/2016\/03\/espigueiros-de-lindoso-el-mas-bello.html\">Un gran ejemplo de la belleza Etnogr\u00e1fica\u00a0<\/a><\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/horreos-de-lindoso\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/de_wz2nmthiJ1R-bRrb6NVCKJYjoaMD0rXvt_rZ6r0MMhyB9P_n83MuomOdqysnyZ28-or5j8lNprsZm3J4ueHmDUEq4vL9MeALvWUi6DAJnQUrGNrvJbyjD-afTVTfIWX2YMxytlKSYcL20gUZ4bvPrV5mZ9nMvFiC8W0tNBYhUw-hafzV1A2r3pcYsh8hTLOa1Y4CgDNyjXn75_qJnBXycQaGLWVZbMAWfllc_Br3JT7nBTD_p71cPMIa4dVAZxOMWk1kWKuAyaY7Py3F7f6-H_BK3c3yjoCN5wQYfzqEphdMklB8Vcf0hDvB3dxpd7_AfsMo893VeYxWmmdVXIb2qdEz7b4oNEl9pK7qQU6OhLHDPl8Az2r6wHBYrHPmtcMcT7Igk0JLOKY_-JdRaspk-utpJJ05OpMwfFrFxrbOMejtWC4gjTnxFFQP9w_XSplSr2fhDU9Do4SHjryt9uY6Y9QisfOQ_Ea0jtM0BO7agkIq-zeaW4zIBq4M76KIwLGfJTNBOScVFuQKIbtLLwxcStukP9lv2Pqhxzdf61kwoei8ttU-uoCESY9XUEOJlY45Il63IM1ybFwoaWgQEvlAk4KVxuaJ4uhofrFOSW5E=w1368-h769-no\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">El museo cuesta 1,50 euros por adultos y ni\u00f1@s hasta 11 a\u00f1os gratis,<\/p>\n<p style=\"text-align: center;\">os recomendamos la visita.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.turismoenportugal.org\/castillo-de-lindoso\">HORARIOS<\/a><\/p>\n<p><a href=\"https:\/\/www.turismoenportugal.org\/castillo-de-lindoso\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/omULnkFdXa1uXe8lczrnexz8G0IYzfrH8lNPPD7Y1uTN_JZ-3TAGYO8cZ7hhjLas7bFlTlq-EE8Y-nN1vTub2fxV0o1p1CKbPMmfpMmCqVQvb51helYPpZsLof2E-_ejMFUZZhGY3mjuefb6rO9pjI4ECQUwEIwzmIaG4Hh12oUrGx61JX3HpoE-D2zvCB3zR4-L4pEyMjLEDUURwrxetw4Gi9goDrBEdAIpS1EZcNg3TXmgzSI7HKZ2b95kkXEUErNSrbFv67RcElo9ASFu_DK6DNArWpEQZ2rU3kBf7-kbWLZEjUl6OUDA5Upcry5u3XO43C350DDVAmpLe5Bnas3KMc74Ysi1-BnEdY-TyavZORMe3UaD3JmTVxpLhgn5jA54e-t2N-HX7l6GME2XiLS1wCRnRs9NNDODrcBbsu6ie28_wL56G_spFwT1yV8l862ONP_WBKg3SSRwkgvm-guE7gp3ZdOPIMHRZWPfxLNLAZC2Aq2ZblhvF--8FKtu_L5eyzFuSflTm6Yi3NurlPxw5jClh72mwqpJ1LCaVi9Nvy8CDuLkSI4yXRRtFWfXKg-gpDavq2iQ9TSyne8uYteVQjY9XqSJyDEVJmtGEOY=s769-no\" alt=\"\" width=\"769\" height=\"769\" \/><\/a><\/p>\n<h4 style=\"text-align: center;\">\u00bfNos damos una vuelta alrededor del <a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castillo-lindoso\/\">castillo<\/a>?<\/h4>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castillo-lindoso\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/yZYnSsSoOdg528Uks1_jAWw25bUyIc4tF43NdbE5rVbnDpRABzHEKXBFT5L7UQMlHkIUqCx-3U4OaHBG1yf7ecmCV2dbrLtrDn__CViYkhWoecqNUy564iXPNQVPCYDNt4Wqg9s-yqKcph5y8mKoLgpFZWG-EjemJCX6uybVCi29mTXLiy0MoXjrvraMe3L7hVCOXzGqvxCLQxqHL-ymGAbj8q9I6Vf2_CV6H75DkfRm87_IyQUiiAj-TDIVqI9LnTaX83BtEaKd0a51fRoC2fE_hdoHg81rlN3sE0C99zCMjWDNF3YSWMk6UKM5tOj5UV9l8BkWQXDgliCGIhvMqLjPqUD_5JUx92noW1aQ8fu-Y8_KdHSIPGPEJ74kjDqWNc8io4WrZmEUbeaPv8pgag_ZnTRfZCXxo6ALhTerqs_wJz9VOu8bFQ381F4gOaOxP1M6-e6_Y8HSMrXmMc0KtaAnufSVaLc1nsf3TzAh4hC9pTc3_mh5sI-_Dmug4t3Gygrjopw75mFkqC0aRg2-iQtSXvfgOnt5q6_Fjcwo2Ba87Ods8_RwjEaJlDX4iTX5gBMar0Var3JJUtfV9LqA5xeERfNhVFeu5DO1SQeLr5U=w1368-h769-no\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<h1 style=\"text-align: center;\">RETO de aproximaci\u00f3n<\/h1>\n<p style=\"text-align: center;\">\u00bfCU\u00c1NTOS <a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/horreos-de-lindoso\/\">H\u00d3RREOS<\/a> TIENE EL CONJUNTO?<\/p>\n<p style=\"text-align: center;\">\u00bfQui\u00e9n se acercar\u00e1 m\u00e1s a la cifra? los contamos \u00bfseremos capaces?<\/p>\n<p style=\"text-align: center;\">Buscamos el que m\u00e1s nos gusta<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/horreos-de-lindoso\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/2tWZCdFj9Hb0aUCiFbhO2lLgdAnXNmurYD1LDGQHHYdCivnBE_TMcYUpuiLTS6CY8YS84n-mtSP1mT7cybAVuCdcKJR1AKc6EZ1O35MNLk6pdtfshnCI83V6wnn7lnBXS8bDsMMckiVtUPon5lk5EZKNLKs0RP3nloOs0QFv7n5rffqGStiNCDECBg7erOf94ajTiVRoa0Odx5LgrzO8HDvxOxFZu-rjNK5HZf6ikJrlblF_Ff0qggAcgN5vixLhjCy251iCMQwqr7Gc9TFaiPcgzOMZ4IsqjF791cQlZtVT0-msoALj6ycCzduUaIX88rv1hoBZyTf1FY0ngHpZhia38AwIYGcRViTIrSZIfa-3YRx2Xk-z8vup94rRktdZhNxbA81z0IOiiPt8HvdxZghn-zksRkw6SCwqgQ0eK-6xygGUuJBI_cL3HthPkJhrpkeblgBjN-9pxSMahR2WCvY8yPl9S0apIFzi8bwwSdUvF7dkzS0FV8e8KhNg24hzgT_N3JbN-lUQeAy90SakcknoMY8cqHhcGmcydHdT772rZWDHTHQnCo02DlZTOoMIeLD3strWbXOjIbJ2SMKGKzuNCzpxO5ZiC8H-D98pNOU=s769-no\" alt=\"\" width=\"769\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Nos despedimos de Lindoso sabiendo que volveremos nuevamente porque nos han <a href=\"https:\/\/www.turismoenportugal.org\/que-ver-en-el-parque-nacional-de-peneda-geres\">quedado muchos sitios<\/a> sin visitar por falta de tiempo<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castillo-lindoso\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/uswHNzKN4cYNObh2n-8TZB_ViqvUZ-yfG0mm_A7iorErXmcFETnsuDSB89SGpUijV6ZPpVJ0W5BqQGLaGhPHxfbl9QBxRWXFw4LR4L54JiYyGNTrHlJTAshau_KQ-ToD4pdEQY2seaLUbZcV1vYc0BBFnPmgVvKd5q_ssLRA-xC-XRvfAz_UqE2TUBLVRAN3r854dXLpaD0wP0HwMyOWNAzPdWkBvFIaXufvPcNvZDyQLX5jb7wFN3Le6YxT23QYLF7Hnl0x8EWr7Kuk-xPsHDEnprPmMX-70rXiJePRI62Ear6sRBmGOsQ6VBIwCwsJ_JmtoMJpv7HG8lnS2-ezawvX51krzo5p1eaL-TMFe_4MnR3hy21ofcDO00WHf_n7vJtTjiwD_eQC40092tksyfFMb5Gzp0EXPpOcoO09MQw-Z9IVBHc7NQkuoq1IQMwr88QRtjClw8tOcLboUoLlNLjYnkRSEKl-DyvzTbdJnx_UpfllP9QSx-6PUA4b4bLQpeW41jB-WlAIr75IA_hCt___ln0RtMhk6PTfg0KFFmgBXH8CVajt0QTa1ti8qGONqWENChwL1nH86vdxDu7706ZlaL6CLCulAmbA0ozK1wo=w1368-h769-no\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Un Gran Viaje<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/horreos-de-lindoso\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/g7Vcn8G05DJNjDFA65rDVP1Id3ed6TeZW4IPGHfpcwRXYI9cErZDuN5aGWaLnAKUYIc2E6yRO0ukHT81DfzEFiuapNpQ6-YpDoRf5MsX1WJoKlAOm9dJttTEpcwgijG1_BDuoUAFJJBPS4KPnrGSC9HFMq8f3wL9ro9JvRe8dVBkoD0FS5VbO6fzx0BxTN3A0EfSskmhJ8zXRSwDJZpkBqLif3UNDL2c-Jy6n6eP2JUoCf9B-D76DT4SXozj-wJIG8-a-YNWGHZRqRV45YFMspTlnN32K8t8tDIXPVqCvRBD8uRMixEcyaFOg98k8n6pJYiHByy6L0H4ooYGK1EQzMwOjLddFQw6_W-d-qpCUJLsrDsFMOdhwFJb1lxqEDcyBeUk3ugur6T9qFAMPmLT-07QBlFZQq9KbrCWIQHChCvD1g0nYwbUlKu-QDcyM2F5I9grlxqRA675u1oMeEIrzJyQLt9R476AGRw919dFkrzvA6CbWAZV3MXqrcLtwdRiUBAZP6lWbm2LGjfoTxBmCDWFnOPfwpQN9ZBUvk2D4Y2kzqdXvSmvCgQ6aBCCKTebjXZBLrrA7NE1iQXWtDRN6ZuR7sbDnVn2RTUj634ulz8=w1368-h769-no\" alt=\"\" width=\"1367\" height=\"769\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Recuerda que en los enlaces que est\u00e1n de otro color y subrayados y pinchando a las fotos<\/p>\n<p style=\"text-align: center;\">ten\u00e9is m\u00e1s informaci\u00f3n<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/horreos-de-lindoso\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/-rur-ikD2nhLYoh5aDMImdpMo3WMi8SuKvLk-qGWyKX0mLB2OzmanAm9BGDQMq7zmMHjtZ7I9AnJlwO1m0lokJw_giMYsMsAS0f8M9Y2uzT1LbmbO0xMDVkgpnmeUShPqL3g5dX_5ztfV_5N0wBv-kQVA0kM5CfARuX0-4EPkIHVScN9ZmMvw5xv_63xC1jeXE71-zT11XqZcqBzZckMfdv1UDkczccXTxz3tTS6zoaPlFcVrU8NqBkR8MVFr1ogduMob48yJCHuegZItWqcFY6T1R-MIgMLoU-Xj7ZLu4D5sHj_A3hu9fOel4J2R-vLNIoRxsC8H0Y8HZOmcQOO-0R8a0C_NZQ_z2vfU1yco7ZBMOfR4I4WBIVjBdUaXEjmPUpolr4GN_ybqgsTjJypZrH3V3fSz2ctrvZeetDzjiOwHFgzIBBz1SYL7BVu0bCeHa6meajtmzWG37WpFpVateLEGsV7koDGnOWPicyj2oAPZBZaLGCVR3RXRj4V0z_-GMDaKQfzfpLx5J7iKyhSRd2dyTBxXmbkdHMBNBQhA-3NVPkUEFrb7ewZBFyQdjVTAf6e7-RTex0Rsw_2OfOeEHMpqFis3d41RtnDT41pIGQ=w433-h769-no\" alt=\"\" width=\"433\" height=\"769\" \/><\/a><\/p>\n<h4 style=\"text-align: center;\">PORQUE NO TODO EN UN VIAJE ES JUGAR<\/h4>\n<h2 style=\"text-align: center;\">O S\u00cd!!!<\/h2>\n<figure style=\"width: 836px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.youtube.com\/watch?v=8lgg2uksjsc\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afce77f70a.jpg\" alt=\"\" width=\"836\" height=\"371\" \/><\/a><figcaption class=\"wp-caption-text\">Lindoso desde el aire<\/figcaption><\/figure>\n<h1 style=\"text-align: center;\">ESPERAMOS OS HAYA GUSTADO LA ENTRADA<\/h1>\n<h1 style=\"text-align: center;\">OS INVITAMOS A HACER ESTE VIAJE VUESTRO<\/h1>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.galiciamaxica.eu\/\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lh3.googleusercontent.com\/tfHEqx3NNMpARAQKH69BT2-HBo5ige28X6nXFaVjCj53HH5SCUEpabcpxPD4U7ibLB_383eTWeD8PHI6bqK3S5_egekRvd5Et41HZ6vkWsh1pLNoMMH7Z-yWfIybd_aXoKeR_4tjo26CueE8qTr0ZzFWaGpUmQZKqi24DXf4Iq4G8Lah81U81hKDhOKqkbs9lc8Apnidv2B30g_ENfysYRiYasneSgsGDHfiZaAs8FC4ii_jDy9kCTznd5qUtyO6qL15l_BNosQkPMPy4hrVDe2WtCBHKt-cgvaThpF07_9amweR6LyJjfuou3luSHJzTIiMbNVY2NZZ8bV0ZyDTluZa8whNftFwlq4uHRWHPgDqDjXKalE2jR9vrgY8_3oOo7SdAktxtv8tEVm0eKi6eBVhxjCj-SxMKS5GX4soFeleicpOtBuNYhZvaewUv_yMmPZrXTd5X7RIv0axrgbL1HjVfF-_eXRDdwXPmFtWdcsbjyaqbVC8VRCtMJ2aS_QDCvoBswEG_-DHXiS-YkcIRrDgqyJXle4L0fA5_SfOrweBdI_51nguqmGGttJq4DVmQZipdzS4k9mxxu4CjyyQhPx5kt16-BVD8ewfYg1_-Aw=w370-h523-no\" alt=\"\" width=\"439\" height=\"621\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><strong><em>\u201cLa vida es una oportunidad, benef\u00edciate de ella. La vida es belleza, adm\u00edrala. La vida es un sue\u00f1o, alc\u00e1nzalo. La vida es un desaf\u00edo, enfr\u00e9ntalo. La vida es un juego, ju\u00e9galo.\u201d\u00a0 Madre Teresa<\/em><\/strong><\/p>\n<p id=\"leyenda\">\n<p>Sancha Rodr\u00edguez era hija de Aras Pardo y de Tareyga Affonso. Se cas\u00f3 con Fern\u00e1n P\u00e9rez de Andrade con \u00e9l tuvo dos hijas, Sancha e Yn\u00e9s, y dos hijos Nu\u00f1o y Pedro \u00abos fill\u00f3s erdeiro\u00bb. Las hijas las enviaron al monasterio de Santa Clara de Santiago.<br \/>\nDo\u00f1a Sancha heredo de sus padres varios se\u00f1or\u00edos entre ellos los de Soutomaior, Casti\u00f1eira y Fornelos .<br \/>\nEn aquel tiempo hab\u00eda en Galicia, lo que denominaron <strong>\u00aba luta da fronteira\u00bb \u201cguerra de la frontera\u201d<\/strong>, donde las m\u00e1s poderosas familias de la nobleza <strong>gallega (Orden da Banda)<\/strong> y la <strong>portuguesa (Orden de Cristo)<\/strong>, estaban enfrentadas por el control de los dominios. Entre aquellas familias se encontraban los de conde de Barcelos en el castillo Castro Laboreiro (Viana do Castelo) pertenecientes a la Orden de Cristo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/55577ae1c1562s63508_p.jpg\" width=\"600\" height=\"389\" \/><br \/>\nPronto tuvo Sancha la desgracia de quedarse sola, pues su marido que a\u00fan no ten\u00eda el t\u00edtulo de conde, se fue a guerrear al lado de Enrique II contra Pedro I de Portugal.<br \/>\n<strong>Nu\u00f1o y Pedro<\/strong>, hijos de do\u00f1a Sancha, contaban ya con diecinueve a\u00f1os uno y dieciocho el otro, y hab\u00edan entablado cierta amistad con los hermanos de la familia Barcelos, Sim\u00f3n y Alonso, pertenecientes al bando contrario (Orden de Cristo). Un d\u00eda jugando Pedro con los hermanos Barcelos, en un encontronazo, comenz\u00f3 una disputa, las palabras se elevaron, hasta que todo fue a m\u00e1s y echaron manos a sus espadas. Pero esta lucha no iba a ser justa, Pedro, se hallaba s\u00f3lo, mientras que los dos hermanos Barcelos se encontraban en compa\u00f1\u00eda de sus criados. Todos fueron contra \u00e9l, y ante tras desigual cruce de espadas fue vilmente asesinado por los Barcelos.<br \/>\nCuando uno de los Barcelos dijo:<br \/>\n\u201cNo podemos quedarnos aqu\u00ed debemos irnos, pues cuando la muerte llegue a o\u00eddos de su hermano buscar\u00e1 venganza, vayamos a la casa de vuestro padre.\u201d<br \/>\nTen\u00eda fama el mayor de los Andrade de buen manejo de la espada:<br \/>\n\u201cNo, hermano si huimos ahora, su venganza ser\u00e1 terrible. Debemos adelantarnos a sus actos, enviemos alg\u00fan mozo en su b\u00fasqueda antes de que la noticia de la muerte llegue a sus o\u00eddos, y sin esper\u00e1rselo le daremos muerte tambi\u00e9n.\u201d<br \/>\n\u201cAs\u00ed lo haremos.\u201d -Respondi\u00f3 el otro hermano.-<br \/>\nMandaron pues sin demora a uno de sus m\u00e1s fieles criados.<br \/>\nAguardaron su llegada escondidos en una de las calles por donde sol\u00edan llegar los Andrade. Con las espadas desenvainadas, cuando vieron aparecer al mayor de los Andrade, se abalanzaron sobre \u00e9l, que sin tiempo de respuesta nada pudo hacer, d\u00e1ndole una muerte cruel y cobarde.<br \/>\nAndrade agonizante sin entender nada se preguntaba:<br \/>\n\u201c\u00bfPor qu\u00e9? \u00bfPor qu\u00e9?\u201d -Repet\u00eda balbuceante entre sangre.<\/p>\n<p><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afce94d3b8.jpg\" width=\"1300\" height=\"919\" \/><\/a><br \/>\nMuerto el \u00faltimo var\u00f3n de los Andrade y el padre guerreando, ya no tem\u00edan por sus vidas. Dejando el cuerpo atr\u00e1s, se dirigieron a la casa de su padre que tras explicarle, a su manera, lo sucedido, les aconsej\u00f3 que marcharan de inmediato hacia tierras de Portugal, para asegurarse de las posibles represalias por parte del bando de la Orden da Banda. Y as\u00ed huyeron de Castro Laboreiro. Llevaron los familiares los cuerpos de los Andrade ante su madre, do\u00f1a Sancha, relat\u00e1rosle la atroz muerte a que hab\u00edan sido sometidos sus hijos. Todos cre\u00edan que ante tan tr\u00e1gica y cruel perdida do\u00f1a Sancha, por ser mujer, se hundir\u00eda en la tristeza, en el llanto y que su vida por amor perder\u00eda o loca se volver\u00eda, m\u00e1s alejados de la realidad estaban, do\u00f1a Sancha con gran aplomo ante sus sentimientos, sin soltar l\u00e1grima ni llanto alguno se acerc\u00f3 a sus hijos y los bendijo.<br \/>\n\u201cYo os bendigo hijos m\u00edos, id en paz con Dios, que justa venganza recibir\u00e9is.\u201d<br \/>\nAnte el asombro de los reunidos, les dijo con el coraz\u00f3n endurecido y con un valor encomiable ante los cuerpos yacentes de estos.<br \/>\n\u201cDisponed vosotros el entierro de mis adorables hijos, que yo junto aquellos que quieran acompa\u00f1arme, me dispongo a partir esta misma noche tras los asesinos y hacer justicia.\u201d<br \/>\n\u201c\u00a1Vos! \u2013Dijeron algunos de los parientes-<br \/>\n\u201cMujer soy m\u00e1s, a falta de valor de los presentes, yo misma impartir\u00e9 justicia y buenos dineros dar\u00e9 a aquellos que me acompa\u00f1en.\u201d -Respondi\u00f3 do\u00f1a Sancha.-<br \/>\nParti\u00f3 Do\u00f1a Sancha hacia su se\u00f1or\u00edo y all\u00ed logr\u00f3 reunir para su causa, hasta un total de veinte caballeros, entre familiares, allegados a la Orden de Cristo y siervos a su servicio, mas para protegerla y por justa venganza, que por los dineros ofrecidos.<br \/>\nAveriguaron que los Barcelos hab\u00edan huido al interior de Portugal y do\u00f1a Sancha as\u00ed les habl\u00f3:<br \/>\n\u201cCuando atraviese esa puerta aqu\u00ed se queda do\u00f1a Sancha Rodr\u00edguez, la mujer, y con vosotros va vuestro capit\u00e1n, y la primera en entablar batalla ser\u00e9, que mas puede el coraz\u00f3n y la justicia que todos los hombres armados.\u201d<br \/>\nY vestida bajo una ligera armadura y con la espada de su hijo mayor, parti\u00f3 a caballo hacia tierras portuguesas.<br \/>\nAl cabo de varias semanas averigu\u00f3 que el lugar donde se escond\u00eda los Barcelos era en una posada de la villa portuguesa de Viseu. Hacia all\u00ed se dirigieron raudos. Esperaron que anocheciera planeando la estrategia.<br \/>\nLlegada la noche al amparo de su oscuridad, se acercaron sigilosamente portando el vig\u00f3n, al primer golpe las puertas sucumbieron, do\u00f1a Sancha fue la primera en entrar espada en ristre, tras ella diez caballeros y los dem\u00e1s quedaron fuera protegiendo las puertas y ventanas de toda la posada, para que nadie entrara y nadie saliera, como se hab\u00eda acordado.<br \/>\nLos Barcelos que se dedicaban a la buena vida de mujeres y vino, no esperaban ser atacados y su sorpresa fue aun mayor al ver como Sancha Rodr\u00edguez Tareygo espada en mano capitaneaba aquellos caballeros, no daban cr\u00e9dito a tal imagen.<br \/>\n\u201cNo puede ser gritaban, no puede ser.\u201d<br \/>\n\u201c<strong>H\u00e1gase justicia,<\/strong> -grit\u00f3 do\u00f1a Sancha- aqu\u00ed y ahora pagareis por vuestros cr\u00edmenes.\u201d<br \/>\nLa lucha fue encarnizada, y do\u00f1a Sancha luch\u00f3 con bravura y valor. Por fin la muerte le sobrevino a los hermanos Barcelos, mas no a manos de ella.<br \/>\nJusto al mes de sus asesinatos, la justicia prometida por do\u00f1a Sancha a sus hijos yacentes se hab\u00eda cumplido.<br \/>\n\u201cJusticia se ha hecho, mi se\u00f1ora, es hora ya de partir antes que los portugueses den cuenta de nuestros actos y apresarnos quieran.\u201d -Dijo uno de los caballeros.-<br \/>\n\u201cAun no, -respondi\u00f3 en\u00e9rgica do\u00f1a Sancha- quiero sus cabezas.\u201d<br \/>\n\u201c\u00a1Mi se\u00f1ora!\u201d -Dijo extra\u00f1ado uno de los caballeros-<br \/>\n\u201cHacedlo, o yo mismo los decapitar\u00e9 con mi espada.\u201d -Replic\u00f3 do\u00f1a Sancha-<br \/>\nHacha en mano, procedieron a cortar sus cabezas, que entregaron aun sangrantes a do\u00f1a Sancha de Monroy, esta con gesto indiferente agarr\u00f3 ambas cabezas por los cabellos e imp\u00e1vida dijo:<br \/>\n\u201cAhora si se ha hecho justicia.\u201d<\/p>\n<figure style=\"width: 1153px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.galiciamaxica.eu\/portugal\/castro-laboreiro\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/10\/img_5d9afceabc4a0.jpg\" alt=\"\" width=\"1153\" height=\"769\" \/><\/a><figcaption class=\"wp-caption-text\"><strong>Gigante<\/strong><\/figcaption><\/figure>\n<p>Tras aquello, dejaron la posada y montando en sus cabalgaduras sin descanso, llegaron en d\u00eda y medio a Baiona. All\u00ed detuvo su caballo do\u00f1a Sancha y sin desmontarse de \u00e9l, pregunt\u00f3 por el lugar donde fueron enterrados sus hijos y respondi\u00e9ronle:<br \/>\n\u201cMi se\u00f1ora, tus hijos fueron enterrados en santa sepultura en la iglesia de Santiago, en la Villa de Suotomaior.\u201d<br \/>\nY sin mediar palabra ante el asombro de los caballeros, arre\u00f3 a su caballo y parti\u00f3 hacia Suotomaior y depositando las cabezas de los Barcelos en sus sepulturas dijo:<br \/>\n<strong>\u201cHijos m\u00edos he aqu\u00ed a vuestros asesinos, descansad ahora en paz.\u201d<\/strong><br \/>\nY tras estas palabras se fue a su casa. Mando construir una fortaleza en Soutomaior con capilla interior, para posteriormente trasladar a sus hijos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los s\u00e1bados tambi\u00e9n est\u00e1n para madrugar porque para un viaje como el de hoy necesitaremos de tiempo Hoy visitaremos tres lugares muy especiales, nos moveremos de Galicia a Portugal y de Portugal a Galicia como si de un viaje espacio-tiempo se tratase para descubrir lugares con muchas historias y leyendas Castro Laboreiro, A\u00a0Escusalla y Lindoso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6922,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[51,586,425],"tags":[898,899,897],"class_list":["post-6891","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ourense","category-portugal","category-viajes-compartidos","tag-escusalla","tag-laboreiro","tag-lindoso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Castro Laboreiro, A Escusalla y Castelo de Lindoso en un d\u00eda - Galicia con ni\u00f1os | GALICIA M\u00c1XICA<\/title>\n<meta name=\"description\" content=\"Castro Laboreiro, Escusalla y Lindoso un tri\u00e1ngulo m\u00e1gico que aportar\u00e1 un viaje top en la agenda.Visitaremos lugares muy especiales de Galicia a Portugal\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Castro Laboreiro, A Escusalla y Castelo de Lindoso en un d\u00eda - Galicia con ni\u00f1os | GALICIA M\u00c1XICA\" \/>\n<meta property=\"og:description\" content=\"Castro Laboreiro, Escusalla y Lindoso un tri\u00e1ngulo m\u00e1gico que aportar\u00e1 un viaje top en la agenda.Visitaremos lugares muy especiales de Galicia a Portugal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/\" \/>\n<meta property=\"og:site_name\" content=\"Galicia con ni\u00f1os | GALICIA M\u00c1XICA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/maria.rodriguezserantes\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/maria.rodriguezserantes\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-30T19:11:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-13T17:18:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.galiciamaxica.eu\/mini\/wp-content\/uploads\/2017\/10\/Captura48.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"seseixa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@seseixa\" \/>\n<meta name=\"twitter:site\" content=\"@seseixa\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"seseixa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"33 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/\"},\"author\":{\"name\":\"seseixa\",\"@id\":\"https:\/\/www.galiciamaxica.eu\/mini\/#\/schema\/person\/2b284fe2fd911000a48d2e8936300179\"},\"headline\":\"Castro Laboreiro, A Escusalla y Castelo de Lindoso en un d\u00eda\",\"datePublished\":\"2017-10-30T19:11:48+00:00\",\"dateModified\":\"2024-08-13T17:18:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/\"},\"wordCount\":3920,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/www.galiciamaxica.eu\/mini\/#\/schema\/person\/2b284fe2fd911000a48d2e8936300179\"},\"image\":{\"@id\":\"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.galiciamaxica.eu\/mini\/wp-content\/uploads\/2017\/10\/Captura48.jpg\",\"keywords\":[\"escusalla\",\"laboreiro\",\"Lindoso\"],\"articleSection\":[\"OURENSE\",\"PORTUGAL\",\"VIAJES COMPARTIDOS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/\",\"url\":\"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/\",\"name\":\"Castro Laboreiro, A Escusalla y Castelo de Lindoso en un d\u00eda - Galicia con ni\u00f1os | GALICIA M\u00c1XICA\",\"isPartOf\":{\"@id\":\"https:\/\/www.galiciamaxica.eu\/mini\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.galiciamaxica.eu\/mini\/wp-content\/uploads\/2017\/10\/Captura48.jpg\",\"datePublished\":\"2017-10-30T19:11:48+00:00\",\"dateModified\":\"2024-08-13T17:18:38+00:00\",\"description\":\"Castro Laboreiro, Escusalla y Lindoso un tri\u00e1ngulo m\u00e1gico que aportar\u00e1 un viaje top en la agenda.Visitaremos lugares muy especiales de Galicia a Portugal\",\"breadcrumb\":{\"@id\":\"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/#primaryimage\",\"url\":\"https:\/\/www.galiciamaxica.eu\/mini\/wp-content\/uploads\/2017\/10\/Captura48.jpg\",\"contentUrl\":\"https:\/\/www.galiciamaxica.eu\/mini\/wp-content\/uploads\/2017\/10\/Captura48.jpg\",\"width\":768,\"height\":768,\"caption\":\"img_5d9afc6363837\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.galiciamaxica.eu\/mini\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Castro Laboreiro, A Escusalla y Castelo de Lindoso en un d\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.galiciamaxica.eu\/mini\/#website\",\"url\":\"https:\/\/www.galiciamaxica.eu\/mini\/\",\"name\":\"Galicia con ni\u00f1os | GALICIA M\u00c1XICA\",\"description\":\"Qu\u00e9 hacer con ni\u00f1os en Galicia\",\"publisher\":{\"@id\":\"https:\/\/www.galiciamaxica.eu\/mini\/#\/schema\/person\/2b284fe2fd911000a48d2e8936300179\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.galiciamaxica.eu\/mini\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/www.galiciamaxica.eu\/mini\/#\/schema\/person\/2b284fe2fd911000a48d2e8936300179\",\"name\":\"seseixa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.galiciamaxica.eu\/mini\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/02\/seseixa.png\",\"contentUrl\":\"https:\/\/www.galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/02\/seseixa.png\",\"width\":100,\"height\":100,\"caption\":\"seseixa\"},\"logo\":{\"@id\":\"https:\/\/www.galiciamaxica.eu\/mini\/#\/schema\/person\/image\/\"},\"description\":\"En la actualidad combinando dos proyectos que me apasionan, Galicia y los ni\u00f1os. Tengo mucho que aportar y otro tanto que aprender, as\u00ed como, el tiempo y el coraz\u00f3n, dividido en todo momento. Soy mam\u00e1, un titulo otorgado a tiempo completo, compa\u00f1era y amiga, a todas horas, familiar y cercana, siempre. De esp\u00edritu inquieto, soy una eterna ni\u00f1a que juega en el pa\u00eds de las maravillas. Una enamorada de mi tierra, por la que trabajo sin descanso. Creo en la infancia como motor que cambiar\u00e1 el mundo a mejor y busco en mi vida la felicidad como estado permanente porque s\u00f3lo se vive una vez.\",\"sameAs\":[\"http:\/\/mini.galiciamaxica.eu\/\",\"https:\/\/www.facebook.com\/maria.rodriguezserantes\",\"https:\/\/x.com\/seseixa\"],\"url\":\"https:\/\/www.galiciamaxica.eu\/mini\/author\/seseixa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Castro Laboreiro, A Escusalla y Castelo de Lindoso en un d\u00eda - Galicia con ni\u00f1os | GALICIA M\u00c1XICA","description":"Castro Laboreiro, Escusalla y Lindoso un tri\u00e1ngulo m\u00e1gico que aportar\u00e1 un viaje top en la agenda.Visitaremos lugares muy especiales de Galicia a Portugal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/","og_locale":"es_ES","og_type":"article","og_title":"Castro Laboreiro, A Escusalla y Castelo de Lindoso en un d\u00eda - Galicia con ni\u00f1os | GALICIA M\u00c1XICA","og_description":"Castro Laboreiro, Escusalla y Lindoso un tri\u00e1ngulo m\u00e1gico que aportar\u00e1 un viaje top en la agenda.Visitaremos lugares muy especiales de Galicia a Portugal","og_url":"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/","og_site_name":"Galicia con ni\u00f1os | GALICIA M\u00c1XICA","article_publisher":"https:\/\/www.facebook.com\/maria.rodriguezserantes","article_author":"https:\/\/www.facebook.com\/maria.rodriguezserantes","article_published_time":"2017-10-30T19:11:48+00:00","article_modified_time":"2024-08-13T17:18:38+00:00","og_image":[{"width":768,"height":768,"url":"https:\/\/www.galiciamaxica.eu\/mini\/wp-content\/uploads\/2017\/10\/Captura48.jpg","type":"image\/jpeg"}],"author":"seseixa","twitter_card":"summary_large_image","twitter_creator":"@seseixa","twitter_site":"@seseixa","twitter_misc":{"Escrito por":"seseixa","Tiempo de lectura":"33 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/#article","isPartOf":{"@id":"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/"},"author":{"name":"seseixa","@id":"https:\/\/www.galiciamaxica.eu\/mini\/#\/schema\/person\/2b284fe2fd911000a48d2e8936300179"},"headline":"Castro Laboreiro, A Escusalla y Castelo de Lindoso en un d\u00eda","datePublished":"2017-10-30T19:11:48+00:00","dateModified":"2024-08-13T17:18:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/"},"wordCount":3920,"commentCount":2,"publisher":{"@id":"https:\/\/www.galiciamaxica.eu\/mini\/#\/schema\/person\/2b284fe2fd911000a48d2e8936300179"},"image":{"@id":"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.galiciamaxica.eu\/mini\/wp-content\/uploads\/2017\/10\/Captura48.jpg","keywords":["escusalla","laboreiro","Lindoso"],"articleSection":["OURENSE","PORTUGAL","VIAJES COMPARTIDOS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/","url":"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/","name":"Castro Laboreiro, A Escusalla y Castelo de Lindoso en un d\u00eda - Galicia con ni\u00f1os | GALICIA M\u00c1XICA","isPartOf":{"@id":"https:\/\/www.galiciamaxica.eu\/mini\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/#primaryimage"},"image":{"@id":"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.galiciamaxica.eu\/mini\/wp-content\/uploads\/2017\/10\/Captura48.jpg","datePublished":"2017-10-30T19:11:48+00:00","dateModified":"2024-08-13T17:18:38+00:00","description":"Castro Laboreiro, Escusalla y Lindoso un tri\u00e1ngulo m\u00e1gico que aportar\u00e1 un viaje top en la agenda.Visitaremos lugares muy especiales de Galicia a Portugal","breadcrumb":{"@id":"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/#primaryimage","url":"https:\/\/www.galiciamaxica.eu\/mini\/wp-content\/uploads\/2017\/10\/Captura48.jpg","contentUrl":"https:\/\/www.galiciamaxica.eu\/mini\/wp-content\/uploads\/2017\/10\/Captura48.jpg","width":768,"height":768,"caption":"img_5d9afc6363837"},{"@type":"BreadcrumbList","@id":"https:\/\/www.galiciamaxica.eu\/mini\/castro-laboreiro-a-escusalla-y-castelo-de-lindoso-en-un-dia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.galiciamaxica.eu\/mini\/"},{"@type":"ListItem","position":2,"name":"Castro Laboreiro, A Escusalla y Castelo de Lindoso en un d\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/www.galiciamaxica.eu\/mini\/#website","url":"https:\/\/www.galiciamaxica.eu\/mini\/","name":"Galicia con ni\u00f1os | GALICIA M\u00c1XICA","description":"Qu\u00e9 hacer con ni\u00f1os en Galicia","publisher":{"@id":"https:\/\/www.galiciamaxica.eu\/mini\/#\/schema\/person\/2b284fe2fd911000a48d2e8936300179"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.galiciamaxica.eu\/mini\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/www.galiciamaxica.eu\/mini\/#\/schema\/person\/2b284fe2fd911000a48d2e8936300179","name":"seseixa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.galiciamaxica.eu\/mini\/#\/schema\/person\/image\/","url":"https:\/\/www.galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/02\/seseixa.png","contentUrl":"https:\/\/www.galiciamaxica.eu\/mini\/wp-content\/uploads\/2019\/02\/seseixa.png","width":100,"height":100,"caption":"seseixa"},"logo":{"@id":"https:\/\/www.galiciamaxica.eu\/mini\/#\/schema\/person\/image\/"},"description":"En la actualidad combinando dos proyectos que me apasionan, Galicia y los ni\u00f1os. Tengo mucho que aportar y otro tanto que aprender, as\u00ed como, el tiempo y el coraz\u00f3n, dividido en todo momento. Soy mam\u00e1, un titulo otorgado a tiempo completo, compa\u00f1era y amiga, a todas horas, familiar y cercana, siempre. De esp\u00edritu inquieto, soy una eterna ni\u00f1a que juega en el pa\u00eds de las maravillas. Una enamorada de mi tierra, por la que trabajo sin descanso. Creo en la infancia como motor que cambiar\u00e1 el mundo a mejor y busco en mi vida la felicidad como estado permanente porque s\u00f3lo se vive una vez.","sameAs":["http:\/\/mini.galiciamaxica.eu\/","https:\/\/www.facebook.com\/maria.rodriguezserantes","https:\/\/x.com\/seseixa"],"url":"https:\/\/www.galiciamaxica.eu\/mini\/author\/seseixa\/"}]}},"amp_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.galiciamaxica.eu\/mini\/wp-json\/wp\/v2\/posts\/6891"}],"collection":[{"href":"https:\/\/www.galiciamaxica.eu\/mini\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.galiciamaxica.eu\/mini\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.galiciamaxica.eu\/mini\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.galiciamaxica.eu\/mini\/wp-json\/wp\/v2\/comments?post=6891"}],"version-history":[{"count":5,"href":"https:\/\/www.galiciamaxica.eu\/mini\/wp-json\/wp\/v2\/posts\/6891\/revisions"}],"predecessor-version":[{"id":22118,"href":"https:\/\/www.galiciamaxica.eu\/mini\/wp-json\/wp\/v2\/posts\/6891\/revisions\/22118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.galiciamaxica.eu\/mini\/wp-json\/wp\/v2\/media\/6922"}],"wp:attachment":[{"href":"https:\/\/www.galiciamaxica.eu\/mini\/wp-json\/wp\/v2\/media?parent=6891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.galiciamaxica.eu\/mini\/wp-json\/wp\/v2\/categories?post=6891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.galiciamaxica.eu\/mini\/wp-json\/wp\/v2\/tags?post=6891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}